{"id":22858,"date":"2026-03-11T16:09:45","date_gmt":"2026-03-11T16:09:45","guid":{"rendered":"https:\/\/esi.uclm.es\/?p=22858"},"modified":"2026-03-18T11:33:45","modified_gmt":"2026-03-18T11:33:45","slug":"18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial","status":"publish","type":"post","link":"https:\/\/esi.uclm.es\/index.php\/2026\/03\/11\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\/","title":{"rendered":"18M &#8211; Dise\u00f1o de Gemelos Digitales de Consumidores con Simulaci\u00f3n Social e Inteligencia Artificial"},"content":{"rendered":"\n<p>La Escuela Superior de Inform\u00e1tica acoger\u00e1 el pr\u00f3ximo 18 de marzo, a las 11:30 h, en el Sal\u00f3n de Actos Alan Turing, la conferencia titulada <strong>\u00abDise\u00f1o de Gemelos Digitales de Consumidores con Simulaci\u00f3n Social e Inteligencia Artificial<\/strong>\u00bb, que ser\u00e1 impartida por <strong>Oscar Cord\u00f3n, <\/strong>Catedr\u00e1tico de Inteligencia Artificial de la <a href=\"https:\/\/www.ugr.es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Universidad de Granada<\/a>.<\/p>\n\n\n\n<p>En esta charla se abordar\u00e1 la aplicaci\u00f3n de diferentes tecnolog\u00edas de Simulaci\u00f3n Social, Ciencia de Redes e Inteligencia Artificial al dise\u00f1o de gemelos digitales de personas reales y, en particular, de consumidores y votantes. La sesi\u00f3n comenzar\u00e1 con una revisi\u00f3n del objetivo principal y de las tecnolog\u00edas empleadas, profundizando en t\u00e9cnicas avanzadas de simulaci\u00f3n social, como los <strong>Modelos Basados en Agentes (Agent-Based Models, ABMs)<\/strong>.<\/p>\n\n\n\n<div class=\"esi-charla-ficha\" role=\"article\" aria-label=\"Ficha de conferencia\">\n  <div class=\"esi-charla-etiqueta\">Conferencia<\/div>\n  \n  <h2 class=\"esi-charla-titulo\">\n    Dise\u00f1o de Gemelos Digitales de Consumidores con Simulaci\u00f3n Social e Inteligencia Artificial\n  <\/h2>\n  \n  <p class=\"esi-charla-ponente\">\n    <strong>Ponente:<\/strong> Oscar Cord\u00f3n<br>\n    <span>Catedr\u00e1tico de Inteligencia Artificial, Universidad de Granada<\/span>\n  <\/p>\n\n  <div class=\"esi-charla-datos\">\n    <div class=\"esi-charla-item\">\n      <span class=\"esi-charla-label\">Fecha<\/span>\n      <span class=\"esi-charla-value\">18 de marzo<\/span>\n    <\/div>\n    <div class=\"esi-charla-item\">\n      <span class=\"esi-charla-label\">Hora<\/span>\n      <span class=\"esi-charla-value\">11:30 h<\/span>\n    <\/div>\n    <div class=\"esi-charla-item\">\n      <span class=\"esi-charla-label\">Lugar<\/span>\n      <span class=\"esi-charla-value\">Sal\u00f3n de Actos Alan Turing<\/span>\n    <\/div>\n    <div class=\"esi-charla-item\">\n      <span class=\"esi-charla-label\">Organiza<\/span>\n      <span class=\"esi-charla-value\">Escuela Superior de Inform\u00e1tica<\/span>\n    <\/div>\n  <\/div>\n\n  <div class=\"esi-charla-resumen\">\n    <p>\n      La charla abordar\u00e1 la aplicaci\u00f3n de tecnolog\u00edas de Simulaci\u00f3n Social, Ciencia de Redes e Inteligencia Artificial\n      al dise\u00f1o de gemelos digitales de personas reales, especialmente consumidores y votantes, mediante modelos\n      avanzados basados en agentes y casos de estudio en marketing, comportamiento del consumidor y comunicaci\u00f3n pol\u00edtica.\n    <\/p>\n  <\/div>\n<\/div>\n\n<style>\n  .esi-charla-ficha {\n    box-sizing: border-box;\n    max-width: 780px;\n    margin: 1.5rem auto;\n    padding: 1.5rem;\n    border: 1px solid #d9dee5;\n    border-radius: 14px;\n    background: #ffffff;\n    box-shadow: 0 6px 20px rgba(0, 0, 0, 0.06);\n    font-family: Arial, Helvetica, sans-serif;\n    color: #1f2937;\n  }\n\n  .esi-charla-etiqueta {\n    display: inline-block;\n    margin-bottom: 0.9rem;\n    padding: 0.35rem 0.7rem;\n    border-radius: 999px;\n    background: #eef4ff;\n    color: #1d4ed8;\n    font-size: 0.82rem;\n    font-weight: 700;\n    letter-spacing: 0.02em;\n    text-transform: uppercase;\n  }\n\n  .esi-charla-titulo {\n    margin: 0 0 0.9rem 0;\n    font-size: 1.8rem;\n    line-height: 1.25;\n    color: #111827;\n  }\n\n  .esi-charla-ponente {\n    margin: 0 0 1.2rem 0;\n    font-size: 1rem;\n    line-height: 1.5;\n    color: #374151;\n  }\n\n  .esi-charla-ponente span {\n    color: #4b5563;\n  }\n\n  .esi-charla-datos {\n    display: grid;\n    grid-template-columns: repeat(auto-fit, minmax(180px, 1fr));\n    gap: 0.9rem;\n    margin: 1.2rem 0 1.4rem 0;\n  }\n\n  .esi-charla-item {\n    padding: 1rem;\n    border-radius: 10px;\n    background: #f8fafc;\n    border: 1px solid #e5e7eb;\n  }\n\n  .esi-charla-label {\n    display: block;\n    margin-bottom: 0.35rem;\n    font-size: 0.85rem;\n    font-weight: 700;\n    color: #6b7280;\n    text-transform: uppercase;\n    letter-spacing: 0.03em;\n  }\n\n  .esi-charla-value {\n    display: block;\n    font-size: 1rem;\n    font-weight: 600;\n    color: #111827;\n  }\n\n  .esi-charla-resumen {\n    padding-top: 1rem;\n    border-top: 1px solid #e5e7eb;\n  }\n\n  .esi-charla-resumen p {\n    margin: 0;\n    font-size: 1rem;\n    line-height: 1.65;\n    color: #374151;\n  }\n\n  @media (max-width: 600px) {\n    .esi-charla-ficha {\n      padding: 1.1rem;\n    }\n\n    .esi-charla-titulo {\n      font-size: 1.45rem;\n    }\n  }\n<\/style>\n\n\n\n<h2 class=\"wp-block-heading\">Casos de estudio<\/h2>\n\n\n\n<p>A continuaci\u00f3n, se presentar\u00e1n tres casos de estudio relacionados con el marketing, el comportamiento del consumidor y la comunicaci\u00f3n pol\u00edtica.<\/p>\n\n\n\n<p>En primer lugar, se mostrar\u00e1 <strong>Twins<\/strong>, una soluci\u00f3n real de anal\u00edtica de marketing concebida como un laboratorio virtual que permite simular mercados competitivos y predecir indicadores clave de rendimiento, como las ventas, el <strong>Word-of-Mouth (WoM)<\/strong> o el reconocimiento de marca. Para ello, combina ABMs, an\u00e1lisis de redes sociales, algoritmos evolutivos y tecnolog\u00edas de marketing de vanguardia, como la <strong>behavioral economics<\/strong>. El sistema modela el comportamiento de los consumidores y permite analizar el impacto de las inversiones en marketing mediante simulaciones de Monte Carlo durante un periodo concreto. Los consumidores virtuales cuentan con una memoria finita en la que almacenan percepciones y reconocimiento de marca dentro del mercado artificial, tomando decisiones de compra racionales basadas en la maximizaci\u00f3n de sus preferencias. Durante la simulaci\u00f3n, los agentes reciben impactos de distintas fuentes externas o <strong>touchpoints<\/strong>, como medios de masas, televisi\u00f3n, radio, Internet o la propia experiencia de uso del producto. Estos impactos modifican su estado mental y pueden generar cascadas de informaci\u00f3n a trav\u00e9s de la red social de consumidores. La plataforma <strong>Twins<\/strong> ha sido utilizada en proyectos de marketing para numerosas empresas nacionales e internacionales de sectores diversos, entre ellas <strong>Coca-Cola Europa, Jaguar\/Land Rover, Foster\u2019s Hollywood, Domino\u2019s Pizza, El Corte Ingl\u00e9s, Telef\u00f3nica, Samsung, CAPSA, WiZink, Pelayo y L\u2019Oreal M\u00e9xico<\/strong>.<\/p>\n\n\n\n<p>Posteriormente, se introducir\u00e1 un <strong>ABM de comunicaci\u00f3n pol\u00edtica<\/strong> que emplea tecnolog\u00edas similares para analizar el impacto en los votantes de la informaci\u00f3n difundida por los medios sobre los atentados terroristas de Madrid del 11 de marzo de 2004, en los d\u00edas previos a las Elecciones Generales del 14 de marzo. Este modelo permite representar las principales opciones pol\u00edticas, la red social de votantes y la cobertura medi\u00e1tica mediante touchpoints. Su dise\u00f1o, validaci\u00f3n y calibraci\u00f3n se apoyan en informes del CIS y en los resultados reales de las elecciones del 14M. A partir de ello, el modelo se utiliza para evaluar distintos escenarios what-if sobre la cobertura medi\u00e1tica y los efectos del boca a oreja (WoM) entre los votantes.<\/p>\n\n\n\n<p>Finalmente, se presentar\u00e1 otro <strong>ABM orientado al an\u00e1lisis del comportamiento del consumidor<\/strong>, centrado en el estudio del mecanismo que explica la din\u00e1mica de opiniones (OD) sobre superestrellas de cine. Las percepciones de los espectadores sobre estas figuras constituyen uno de los factores que ayudan a predecir el \u00e9xito de una pel\u00edcula. La hip\u00f3tesis de partida plantea que la OD sobre estrellas de cine est\u00e1 determinada principalmente por mecanismos emocionales, frente a mecanismos racionales. Para contrastarla, se emplean encuestas de espectadores e informaci\u00f3n p\u00fablica de IMDb con el fin de construir diferentes ABMs destinados a estimar rankings de superestrellas ampliamente conocidas. Estos modelos difieren en el enfoque de OD utilizado. En este contexto, los agentes tambi\u00e9n se ven influidos por mecanismos de comunicaci\u00f3n global o touchpoints, tales como campa\u00f1as reales y noticias relacionadas con las superestrellas y sus pel\u00edculas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Breve cv<\/h2>\n\n\n\n<p>Oscar Cord\u00f3n es Doctor en Inform\u00e1tica por la Universidad de Granada (1997), donde es Catedr\u00e1tico (2011-) y fue Director Fundador de su Centro de Ense\u00f1anzas Virtuales (2001-05) y Delegado de la Rectora (Vicerrector) para la Universidad Digital (2015-2019).<\/p>\n\n\n\n<p>Fue investigador fundador del European Centre for Soft Computing (2006-2015). Ha recibido el premio IEEE CIS Outstanding Early Career Award (2011), el Premio Nacional de Inform\u00e1tica ARITMEL (2014), el grado de IEEE Fellow (2018), el IFSA Fellow (2019), el Reconocimiento de la Asociaci\u00f3n Espa\u00f1ola de IA por su Promoci\u00f3n y su Carrera en el \u00e1rea (2020), el IX Premio a la Trayectoria Profesional TI de CRUE TIC (2022) y el Premio Granada Ciudad de la Ciencia y la Innovaci\u00f3n a la Transferencia de Conocimiento (2022), entre otros reconocimientos.<\/p>\n\n\n\n<p>Fue miembro del Grupo de Expertos que desarroll\u00f3 la Estrategia Espa\u00f1ola de I+D+I en Inteligencia Artificial (2019) y dirige la C\u00e1tedra Amazon-UGR desde 2025.<\/p>\n\n\n\n<p>Ha publicado m\u00e1s de 430 contribuciones cient\u00edficas (incluyendo 141 art\u00edculos de revista JCR-SCI), dirigido 24 tesis doctorales, coordinado 45 proyectos y contratos de investigaci\u00f3n (con un presupuesto global de ~10M\u20ac), y tiene 4 patentes internacionales en explotaci\u00f3n sobre sistemas inteligentes para identificaci\u00f3n forense.<\/p>\n\n\n\n<p>Est\u00e1 incluido en el Top 2% de investigadores m\u00e1s citados en el mundo en Inteligencia Artificial (Fuente: \u2018Ranking of the World Scientists: World\u2019s Top 2% Scientists\u2019, Universidad de Stanford-Elsevier).<\/p>\n\n\n\n<div class=\"esi-profile-links\" role=\"complementary\" aria-label=\"Enlaces de contacto y perfiles\">\n  <h3 class=\"esi-profile-links__title\">Contacto y perfiles acad\u00e9micos<\/h3>\n\n  <div class=\"esi-profile-links__grid\">\n    <a class=\"esi-profile-links__card\" href=\"mailto:ocordon@decsai.ugr.es\">\n      <span class=\"esi-profile-links__name\">E-mail<\/span>\n      <span class=\"esi-profile-links__value\">ocordon@decsai.ugr.es<\/span>\n    <\/a>\n\n    <a class=\"esi-profile-links__card\" href=\"https:\/\/www.linkedin.com\/in\/oscarcordon\/\" target=\"_blank\" rel=\"noopener noreferrer\">\n      <span class=\"esi-profile-links__name\">LinkedIn<\/span>\n      <span class=\"esi-profile-links__value\">Perfil profesional<\/span>\n    <\/a>\n\n    <a class=\"esi-profile-links__card\" href=\"http:\/\/www.researcherid.com\/rid\/F-6672-2011\" target=\"_blank\" rel=\"noopener noreferrer\">\n      <span class=\"esi-profile-links__name\">Researcher ID<\/span>\n      <span class=\"esi-profile-links__value\">F-6672-2011<\/span>\n    <\/a>\n\n    <a class=\"esi-profile-links__card\" href=\"http:\/\/orcid.org\/0000-0001-5112-5629\" target=\"_blank\" rel=\"noopener noreferrer\">\n      <span class=\"esi-profile-links__name\">ORCID<\/span>\n      <span class=\"esi-profile-links__value\">0000-0001-5112-5629<\/span>\n    <\/a>\n\n    <a class=\"esi-profile-links__card\" href=\"https:\/\/scholar.google.com\/citations?user=oUmv8xgAAAAJ&#038;hl=en\" target=\"_blank\" rel=\"noopener noreferrer\">\n      <span class=\"esi-profile-links__name\">Google Scholar<\/span>\n      <span class=\"esi-profile-links__value\">Producci\u00f3n cient\u00edfica<\/span>\n    <\/a>\n  <\/div>\n<\/div>\n\n<style>\n  .esi-profile-links {\n    box-sizing: border-box;\n    max-width: 760px;\n    margin: 1.5rem auto;\n    padding: 1.25rem;\n    border-radius: 16px;\n    background: #f8fafc;\n    border: 1px solid #e2e8f0;\n    font-family: Arial, Helvetica, sans-serif;\n  }\n\n  .esi-profile-links__title {\n    margin: 0 0 1rem 0;\n    font-size: 1.25rem;\n    color: #0f172a;\n  }\n\n  .esi-profile-links__grid {\n    display: grid;\n    grid-template-columns: repeat(auto-fit, minmax(220px, 1fr));\n    gap: 0.9rem;\n  }\n\n  .esi-profile-links__card {\n    display: block;\n    padding: 1rem;\n    border-radius: 14px;\n    background: #ffffff;\n    border: 1px solid #dbe4ee;\n    text-decoration: none;\n    transition: transform 0.15s ease, box-shadow 0.15s ease, border-color 0.15s ease;\n  }\n\n  .esi-profile-links__card:hover,\n  .esi-profile-links__card:focus {\n    transform: translateY(-2px);\n    border-color: #bfd3e6;\n    box-shadow: 0 8px 18px rgba(0, 0, 0, 0.06);\n  }\n\n  .esi-profile-links__name {\n    display: block;\n    margin-bottom: 0.35rem;\n    font-size: 0.82rem;\n    font-weight: 700;\n    text-transform: uppercase;\n    letter-spacing: 0.03em;\n    color: #64748b;\n  }\n\n  .esi-profile-links__value {\n    display: block;\n    font-size: 1rem;\n    font-weight: 600;\n    line-height: 1.45;\n    color: #0f4c81;\n    word-break: break-word;\n  }\n<\/style>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/esi.uclm.es\/assets\/uploads\/2026\/03\/18M_OscarCordon_web2-1024x576.jpg\" alt=\"\" class=\"wp-image-22859\" srcset=\"https:\/\/esi.uclm.es\/assets\/uploads\/2026\/03\/18M_OscarCordon_web2-1024x576.jpg 1024w, https:\/\/esi.uclm.es\/assets\/uploads\/2026\/03\/18M_OscarCordon_web2-300x169.jpg 300w, https:\/\/esi.uclm.es\/assets\/uploads\/2026\/03\/18M_OscarCordon_web2-768x432.jpg 768w, https:\/\/esi.uclm.es\/assets\/uploads\/2026\/03\/18M_OscarCordon_web2-1536x864.jpg 1536w, https:\/\/esi.uclm.es\/assets\/uploads\/2026\/03\/18M_OscarCordon_web2-18x10.jpg 18w, https:\/\/esi.uclm.es\/assets\/uploads\/2026\/03\/18M_OscarCordon_web2-1300x732.jpg 1300w, https:\/\/esi.uclm.es\/assets\/uploads\/2026\/03\/18M_OscarCordon_web2.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>La Escuela Superior de Inform\u00e1tica acoger\u00e1 el pr\u00f3ximo 18 de marzo, a las 11:30 h, en el Sal\u00f3n de Actos Alan Turing, la conferencia titulada \u00abDise\u00f1o de Gemelos Digitales de Consumidores con Simulaci\u00f3n Social e Inteligencia Artificial\u00bb, que ser\u00e1 impartida por Oscar Cord\u00f3n, Catedr\u00e1tico de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":22864,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[619],"tags":[],"class_list":["post-22858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>18M &#8211; Dise\u00f1o de Gemelos Digitales de Consumidores con Simulaci\u00f3n Social e Inteligencia Artificial - Escuela Superior de Inform\u00e1tica de UCLM<\/title>\n<meta name=\"description\" content=\"La ESI celebra el 18 de marzo una conferencia de Oscar Cord\u00f3n sobre inteligencia artificial, simulaci\u00f3n social y gemelos digitales de consumidores.Te dejo tambi\u00e9n una alternativa algo m\u00e1s natural y igualmente fuerte para SEO:\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/esi.uclm.es\/index.php\/2026\/03\/11\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"18M &#8211; Dise\u00f1o de Gemelos Digitales de Consumidores con Simulaci\u00f3n Social e Inteligencia Artificial - Escuela Superior de Inform\u00e1tica de UCLM\" \/>\n<meta property=\"og:description\" content=\"La ESI celebra el 18 de marzo una conferencia de Oscar Cord\u00f3n sobre inteligencia artificial, simulaci\u00f3n social y gemelos digitales de consumidores.Te dejo tambi\u00e9n una alternativa algo m\u00e1s natural y igualmente fuerte para SEO:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esi.uclm.es\/index.php\/2026\/03\/11\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela Superior de Inform\u00e1tica de UCLM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-11T16:09:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-18T11:33:45+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/esi.uclm.es\/assets\/uploads\/2026\/03\/18M_OscarCordon_web-2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"esiuclm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@esiuclm\" \/>\n<meta name=\"twitter:site\" content=\"@esiuclm\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"esiuclm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2026\\\/03\\\/11\\\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2026\\\/03\\\/11\\\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\\\/\"},\"author\":{\"name\":\"esiuclm\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/person\\\/d9a390095e8beeca5aced92acb17a530\"},\"headline\":\"18M &#8211; Dise\u00f1o de Gemelos Digitales de Consumidores con Simulaci\u00f3n Social e Inteligencia Artificial\",\"datePublished\":\"2026-03-11T16:09:45+00:00\",\"dateModified\":\"2026-03-18T11:33:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2026\\\/03\\\/11\\\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\\\/\"},\"wordCount\":1022,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2026\\\/03\\\/11\\\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2026\\\/03\\\/18M_OscarCordon_web-2.webp\",\"articleSection\":[\"General\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2026\\\/03\\\/11\\\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2026\\\/03\\\/11\\\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\\\/\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2026\\\/03\\\/11\\\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\\\/\",\"name\":\"18M &#8211; Dise\u00f1o de Gemelos Digitales de Consumidores con Simulaci\u00f3n Social e Inteligencia Artificial - Escuela Superior de Inform\u00e1tica de UCLM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2026\\\/03\\\/11\\\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2026\\\/03\\\/11\\\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2026\\\/03\\\/18M_OscarCordon_web-2.webp\",\"datePublished\":\"2026-03-11T16:09:45+00:00\",\"dateModified\":\"2026-03-18T11:33:45+00:00\",\"description\":\"La ESI celebra el 18 de marzo una conferencia de Oscar Cord\u00f3n sobre inteligencia artificial, simulaci\u00f3n social y gemelos digitales de consumidores.Te dejo tambi\u00e9n una alternativa algo m\u00e1s natural y igualmente fuerte para SEO:\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2026\\\/03\\\/11\\\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2026\\\/03\\\/11\\\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2026\\\/03\\\/11\\\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2026\\\/03\\\/18M_OscarCordon_web-2.webp\",\"contentUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2026\\\/03\\\/18M_OscarCordon_web-2.webp\",\"width\":1000,\"height\":563,\"caption\":\"Oscar Cord\u00f3n y un gemelo digital\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2026\\\/03\\\/11\\\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/esi.uclm.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"18M &#8211; Dise\u00f1o de Gemelos Digitales de Consumidores con Simulaci\u00f3n Social e Inteligencia Artificial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#website\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/\",\"name\":\"Escuela Superior de Inform\u00e1tica de UCLM en Ciudad Real, Castilla-La Mancha\",\"description\":\"La Escuela Superior de Inform\u00e1tica de Ciudad Real (Castilla-La Mancha), Universidad de Castilla-La Mancha es un centro universitario que imparte el ciclo completo de Ingenier\u00eda en Inform\u00e1tica: grado, m\u00e1ster y doctorado.\",\"publisher\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/esi.uclm.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\",\"name\":\"Escuela Superior de Inform\u00e1tica de UCLM\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2022\\\/03\\\/LogoESI_cabecera-1.png\",\"contentUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2022\\\/03\\\/LogoESI_cabecera-1.png\",\"width\":460,\"height\":184,\"caption\":\"Escuela Superior de Inform\u00e1tica de UCLM\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Escuela-Superior-de-Informtica-543261809027158\",\"https:\\\/\\\/x.com\\\/esiuclm\",\"https:\\\/\\\/www.instagram.com\\\/esiuclm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/esiuclm\",\"https:\\\/\\\/www.twitch.tv\\\/esiuclm\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/12656631\\\/admin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/person\\\/d9a390095e8beeca5aced92acb17a530\",\"name\":\"esiuclm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"caption\":\"esiuclm\"},\"sameAs\":[\"https:\\\/\\\/esi.uclm.es\"],\"url\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/author\\\/esiadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"18M &#8211; Dise\u00f1o de Gemelos Digitales de Consumidores con Simulaci\u00f3n Social e Inteligencia Artificial - Escuela Superior de Inform\u00e1tica de UCLM","description":"La ESI celebra el 18 de marzo una conferencia de Oscar Cord\u00f3n sobre inteligencia artificial, simulaci\u00f3n social y gemelos digitales de consumidores.Te dejo tambi\u00e9n una alternativa algo m\u00e1s natural y igualmente fuerte para SEO:","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/esi.uclm.es\/index.php\/2026\/03\/11\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\/","og_locale":"es_ES","og_type":"article","og_title":"18M &#8211; Dise\u00f1o de Gemelos Digitales de Consumidores con Simulaci\u00f3n Social e Inteligencia Artificial - Escuela Superior de Inform\u00e1tica de UCLM","og_description":"La ESI celebra el 18 de marzo una conferencia de Oscar Cord\u00f3n sobre inteligencia artificial, simulaci\u00f3n social y gemelos digitales de consumidores.Te dejo tambi\u00e9n una alternativa algo m\u00e1s natural y igualmente fuerte para SEO:","og_url":"https:\/\/esi.uclm.es\/index.php\/2026\/03\/11\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\/","og_site_name":"Escuela Superior de Inform\u00e1tica de UCLM","article_publisher":"https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158","article_published_time":"2026-03-11T16:09:45+00:00","article_modified_time":"2026-03-18T11:33:45+00:00","og_image":[{"width":1000,"height":563,"url":"http:\/\/esi.uclm.es\/assets\/uploads\/2026\/03\/18M_OscarCordon_web-2.webp","type":"image\/webp"}],"author":"esiuclm","twitter_card":"summary_large_image","twitter_creator":"@esiuclm","twitter_site":"@esiuclm","twitter_misc":{"Escrito por":"esiuclm","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/esi.uclm.es\/index.php\/2026\/03\/11\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\/#article","isPartOf":{"@id":"https:\/\/esi.uclm.es\/index.php\/2026\/03\/11\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\/"},"author":{"name":"esiuclm","@id":"https:\/\/esi.uclm.es\/#\/schema\/person\/d9a390095e8beeca5aced92acb17a530"},"headline":"18M &#8211; Dise\u00f1o de Gemelos Digitales de Consumidores con Simulaci\u00f3n Social e Inteligencia Artificial","datePublished":"2026-03-11T16:09:45+00:00","dateModified":"2026-03-18T11:33:45+00:00","mainEntityOfPage":{"@id":"https:\/\/esi.uclm.es\/index.php\/2026\/03\/11\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\/"},"wordCount":1022,"commentCount":0,"publisher":{"@id":"https:\/\/esi.uclm.es\/#organization"},"image":{"@id":"https:\/\/esi.uclm.es\/index.php\/2026\/03\/11\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\/#primaryimage"},"thumbnailUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2026\/03\/18M_OscarCordon_web-2.webp","articleSection":["General"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/esi.uclm.es\/index.php\/2026\/03\/11\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/esi.uclm.es\/index.php\/2026\/03\/11\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\/","url":"https:\/\/esi.uclm.es\/index.php\/2026\/03\/11\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\/","name":"18M &#8211; Dise\u00f1o de Gemelos Digitales de Consumidores con Simulaci\u00f3n Social e Inteligencia Artificial - Escuela Superior de Inform\u00e1tica de UCLM","isPartOf":{"@id":"https:\/\/esi.uclm.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/esi.uclm.es\/index.php\/2026\/03\/11\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\/#primaryimage"},"image":{"@id":"https:\/\/esi.uclm.es\/index.php\/2026\/03\/11\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\/#primaryimage"},"thumbnailUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2026\/03\/18M_OscarCordon_web-2.webp","datePublished":"2026-03-11T16:09:45+00:00","dateModified":"2026-03-18T11:33:45+00:00","description":"La ESI celebra el 18 de marzo una conferencia de Oscar Cord\u00f3n sobre inteligencia artificial, simulaci\u00f3n social y gemelos digitales de consumidores.Te dejo tambi\u00e9n una alternativa algo m\u00e1s natural y igualmente fuerte para SEO:","breadcrumb":{"@id":"https:\/\/esi.uclm.es\/index.php\/2026\/03\/11\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/esi.uclm.es\/index.php\/2026\/03\/11\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esi.uclm.es\/index.php\/2026\/03\/11\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\/#primaryimage","url":"https:\/\/esi.uclm.es\/assets\/uploads\/2026\/03\/18M_OscarCordon_web-2.webp","contentUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2026\/03\/18M_OscarCordon_web-2.webp","width":1000,"height":563,"caption":"Oscar Cord\u00f3n y un gemelo digital"},{"@type":"BreadcrumbList","@id":"https:\/\/esi.uclm.es\/index.php\/2026\/03\/11\/18m-diseno-de-gemelos-digitales-de-consumidores-con-simulacion-social-e-inteligencia-artificial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/esi.uclm.es\/"},{"@type":"ListItem","position":2,"name":"18M &#8211; Dise\u00f1o de Gemelos Digitales de Consumidores con Simulaci\u00f3n Social e Inteligencia Artificial"}]},{"@type":"WebSite","@id":"https:\/\/esi.uclm.es\/#website","url":"https:\/\/esi.uclm.es\/","name":"Escuela Superior de Inform\u00e1tica de UCLM en Ciudad Real, Castilla-La Mancha","description":"La Escuela Superior de Inform\u00e1tica de Ciudad Real (Castilla-La Mancha), Universidad de Castilla-La Mancha es un centro universitario que imparte el ciclo completo de Ingenier\u00eda en Inform\u00e1tica: grado, m\u00e1ster y doctorado.","publisher":{"@id":"https:\/\/esi.uclm.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esi.uclm.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/esi.uclm.es\/#organization","name":"Escuela Superior de Inform\u00e1tica de UCLM","url":"https:\/\/esi.uclm.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esi.uclm.es\/#\/schema\/logo\/image\/","url":"https:\/\/esi.uclm.es\/assets\/uploads\/2022\/03\/LogoESI_cabecera-1.png","contentUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2022\/03\/LogoESI_cabecera-1.png","width":460,"height":184,"caption":"Escuela Superior de Inform\u00e1tica de UCLM"},"image":{"@id":"https:\/\/esi.uclm.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158","https:\/\/x.com\/esiuclm","https:\/\/www.instagram.com\/esiuclm\/","https:\/\/www.youtube.com\/user\/esiuclm","https:\/\/www.twitch.tv\/esiuclm","https:\/\/www.linkedin.com\/company\/12656631\/admin\/"]},{"@type":"Person","@id":"https:\/\/esi.uclm.es\/#\/schema\/person\/d9a390095e8beeca5aced92acb17a530","name":"esiuclm","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","caption":"esiuclm"},"sameAs":["https:\/\/esi.uclm.es"],"url":"https:\/\/esi.uclm.es\/index.php\/author\/esiadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/22858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/comments?post=22858"}],"version-history":[{"count":4,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/22858\/revisions"}],"predecessor-version":[{"id":22867,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/22858\/revisions\/22867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/media\/22864"}],"wp:attachment":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/media?parent=22858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/categories?post=22858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/tags?post=22858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}