{"id":18166,"date":"2024-03-05T10:00:35","date_gmt":"2024-03-05T10:00:35","guid":{"rendered":"https:\/\/esi.uclm.es\/?p=18166"},"modified":"2024-03-05T10:01:42","modified_gmt":"2024-03-05T10:01:42","slug":"de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data","status":"publish","type":"post","link":"https:\/\/esi.uclm.es\/index.php\/2024\/03\/05\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\/","title":{"rendered":"De las Aulas a la Empresa: Mi Camino desde la Universidad hasta NTT Data"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Por <em>Ra\u00fal Barba<\/em>, exalumno y empleado de NTTData<\/h3>\n\n\n\n<div style=\"height:63px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Navegando el camino entre la Academia y el Mercado Laboral<\/strong><\/h3>\n\n\n\n<p>En la recta final de mi \u00faltimo a\u00f1o de carrera, frente a los \u00faltimos ex\u00e1menes finales y el inicio de mi Trabajo de Fin de Grado, se me present\u00f3 una oportunidad que marcar\u00eda el inicio de una nueva etapa en mi vida: la posibilidad de adentrarme en el mundo laboral de la mano de <a href=\"https:\/\/es.nttdata.com\/\">NTT DATA<\/a>. Hasta ese momento, mi trayectoria hab\u00eda sido fundamentalmente acad\u00e9mica, dedicada por completo a la absorci\u00f3n de conocimientos te\u00f3ricos y su puesta en pr\u00e1ctica. Gracias al <a href=\"https:\/\/alarcos.esi.uclm.es\/\">Grupo de Investigaci\u00f3n Alarcos<\/a> tuve tambi\u00e9n la opci\u00f3n de profundizar a\u00fan m\u00e1s en el mundo de la investigaci\u00f3n, concretamente en el \u00e1rea de la computaci\u00f3n cu\u00e1ntica, que sin duda tuvo su impacto en mi forma de entender el presente y futuro de la ingenier\u00eda inform\u00e1tica tal y como la conocemos. Sin embargo, en aquel momento, la idea de dar el salto hacia la aplicaci\u00f3n pr\u00e1ctica, en un entorno real, de todo aquello que hab\u00eda aprendido durante a\u00f1os era tan emocionante como intimidante.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>tuve tambi\u00e9n la opci\u00f3n de profundizar a\u00fan m\u00e1s en el mundo de la investigaci\u00f3n, concretamente en el \u00e1rea de la computaci\u00f3n cu\u00e1ntica, que sin duda tuvo su impacto en mi forma de entender el presente y futuro de la ingenier\u00eda inform\u00e1tica tal y como la conocemos<\/p>\n<\/blockquote>\n\n\n\n<p>Esta disyuntiva es, desde la experiencia que he tenido y desde aquello que he conocido, bastante com\u00fan en alumnos de \u00faltimos cursos, aunque no por ello deja de ser menos importante, pues de alguna forma marca los pasos futuros que das en tu desarrollo, tanto personal como profesional. La posibilidad de entrar a trabajar en un equipo internacional de NTT DATA supon\u00eda un desaf\u00edo que me brindar\u00eda la oportunidad de trabajar y colaborar con profesionales de diversas culturas y perspectivas, con diferentes formaciones, pero con un objetivo com\u00fan: hacer funcionar tanto al proyecto como al equipo. Claramente, este paso representaba un reto significativo, pero tambi\u00e9n la posibilidad de crecer profesional y personalmente, al enfrentar a un reto \u00fanico y apasionante como el que se me present\u00f3 en aquel momento.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>La posibilidad de entrar a trabajar en un equipo internacional de NTT DATA supon\u00eda un desaf\u00edo que me brindar\u00eda la oportunidad de trabajar y colaborar con profesionales de diversas culturas y perspectivas, con diferentes formaciones, pero con un objetivo com\u00fan: hacer funcionar tanto al proyecto como al equipo<\/p>\n<\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfExiste una intersecci\u00f3n entre ambos mundos?<\/strong><\/h3>\n\n\n\n<p>Contrario a lo que se podr\u00eda pensar, mi incorporaci\u00f3n a NTT DATA no marc\u00f3 el final de mi trayectoria educativa, sino que abri\u00f3 un nuevo cap\u00edtulo de aprendizaje continuo y desarrollo personal. Esta transici\u00f3n no significaba dejar atr\u00e1s los a\u00f1os de estudio sin m\u00e1s; en su lugar, representaba una continuaci\u00f3n de la educaci\u00f3n que hab\u00eda recibido en la ESI. De este modo, en mi puesto de trabajo pude aplicar todo aquello que hab\u00eda aprendido durante el grado, pero tambi\u00e9n pude adquirir nuevos conocimientos t\u00e9cnicos y no t\u00e9cnicos que empleo a diario hasta el d\u00eda de hoy. De hecho, dado que esta posibilidad de compaginar mi trabajo con mi formaci\u00f3n en la universidad fue m\u00e1s que factible durante mi \u00faltima etapa en el grado, cuando termin\u00e9 el grado empec\u00e9 un m\u00e1ster en Inteligencia Artificial, un \u00e1rea que promete ser el futuro de nuestra sociedad y que me resulta de lo m\u00e1s apasionante. <\/p>\n\n\n\n<p>Esta decisi\u00f3n de continuar educ\u00e1ndome mientras trabajaba me permiti\u00f3 no solo aplicar los conocimientos adquiridos en el \u00e1mbito laboral de manera pr\u00e1ctica, sino tambi\u00e9n llevar las experiencias y desaf\u00edos enfrentados en el trabajo de vuelta al aula, digamos que fue una simbiosis perfecta, pues hasta el d\u00eda de hoy me ha permitido maximizar el conocimiento que adquiero, pero tambi\u00e9n su puesta en pr\u00e1ctica, y es algo que me gustar\u00eda transmitir en este art\u00edculo de opini\u00f3n, pues s\u00ed existe una intersecci\u00f3n (y en mi opini\u00f3n muy beneficiosa) entre la formaci\u00f3n acad\u00e9mica y el puesto de trabajo en la empresa privada.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>existe una intersecci\u00f3n (y en mi opini\u00f3n muy beneficiosa) entre la formaci\u00f3n acad\u00e9mica y el puesto de trabajo en la empresa privada.<\/p>\n<\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Algunas conclusiones personales<\/strong><\/h3>\n\n\n\n<p>Mi trayectoria hasta ahora me ha permitido entender que incorporarnos al mundo laboral constituye una oportunidad inigualable para poner en pr\u00e1ctica y ampliar los conocimientos y destrezas adquiridos en la ESI. Esta formaci\u00f3n nos equipa para sobresalir en un mercado laboral cada vez m\u00e1s exigente y competitivo.<\/p>\n\n\n\n<p>A primera vista, la transici\u00f3n de la academia al entorno profesional podr\u00eda parecer un salto considerable; sin embargo, mi experiencia me ha dicho que ambos mundos comparten similitudes m\u00e1s que razonables. Los fundamentos t\u00e9cnicos que hemos dominado y las competencias transversales como la comunicaci\u00f3n y el trabajo en equipo que hemos desarrollado y perfeccionado desde nuestros a\u00f1os en la ESI, se convierten en fundamentos esenciales que se aplican a diario en un \u00e1mbito laboral para el que, sin duda, estamos preparados.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Los fundamentos t\u00e9cnicos que hemos dominado y las competencias transversales como la comunicaci\u00f3n y el trabajo en equipo que hemos desarrollado y perfeccionado desde nuestros a\u00f1os en la ESI, se convierten en fundamentos esenciales que se aplican a diario en un \u00e1mbito laboral para el que, sin duda, estamos preparados.<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Por Ra\u00fal Barba, exalumno y empleado de NTTData Navegando el camino entre la Academia y el Mercado Laboral En la recta final de mi \u00faltimo a\u00f1o de carrera, frente a los \u00faltimos ex\u00e1menes finales y el inicio de mi Trabajo de Fin de Grado, se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18167,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[680],"tags":[],"class_list":["post-18166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>De las Aulas a la Empresa: Mi Camino desde la Universidad hasta NTT Data - Escuela Superior de Inform\u00e1tica de UCLM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/esi.uclm.es\/index.php\/2024\/03\/05\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De las Aulas a la Empresa: Mi Camino desde la Universidad hasta NTT Data - Escuela Superior de Inform\u00e1tica de UCLM\" \/>\n<meta property=\"og:description\" content=\"Por Ra\u00fal Barba, exalumno y empleado de NTTData Navegando el camino entre la Academia y el Mercado Laboral En la recta final de mi \u00faltimo a\u00f1o de carrera, frente a los \u00faltimos ex\u00e1menes finales y el inicio de mi Trabajo de Fin de Grado, se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esi.uclm.es\/index.php\/2024\/03\/05\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela Superior de Inform\u00e1tica de UCLM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-05T10:00:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-05T10:01:42+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/esi.uclm.es\/assets\/uploads\/2024\/03\/rbarba_opinion.png\" \/>\n\t<meta property=\"og:image:width\" content=\"344\" \/>\n\t<meta property=\"og:image:height\" content=\"359\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"esiuclm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@esiuclm\" \/>\n<meta name=\"twitter:site\" content=\"@esiuclm\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"esiuclm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2024\\\/03\\\/05\\\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2024\\\/03\\\/05\\\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\\\/\"},\"author\":{\"name\":\"esiuclm\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/person\\\/d9a390095e8beeca5aced92acb17a530\"},\"headline\":\"De las Aulas a la Empresa: Mi Camino desde la Universidad hasta NTT Data\",\"datePublished\":\"2024-03-05T10:00:35+00:00\",\"dateModified\":\"2024-03-05T10:01:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2024\\\/03\\\/05\\\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\\\/\"},\"wordCount\":970,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2024\\\/03\\\/05\\\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2024\\\/03\\\/rbarba_opinion.png\",\"articleSection\":[\"Opini\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2024\\\/03\\\/05\\\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2024\\\/03\\\/05\\\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\\\/\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2024\\\/03\\\/05\\\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\\\/\",\"name\":\"De las Aulas a la Empresa: Mi Camino desde la Universidad hasta NTT Data - Escuela Superior de Inform\u00e1tica de UCLM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2024\\\/03\\\/05\\\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2024\\\/03\\\/05\\\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2024\\\/03\\\/rbarba_opinion.png\",\"datePublished\":\"2024-03-05T10:00:35+00:00\",\"dateModified\":\"2024-03-05T10:01:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2024\\\/03\\\/05\\\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2024\\\/03\\\/05\\\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2024\\\/03\\\/05\\\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\\\/#primaryimage\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2024\\\/03\\\/rbarba_opinion.png\",\"contentUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2024\\\/03\\\/rbarba_opinion.png\",\"width\":344,\"height\":359,\"caption\":\"Ra\u00fal Barba\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2024\\\/03\\\/05\\\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/esi.uclm.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De las Aulas a la Empresa: Mi Camino desde la Universidad hasta NTT Data\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#website\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/\",\"name\":\"Escuela Superior de Inform\u00e1tica de UCLM en Ciudad Real, Castilla-La Mancha\",\"description\":\"La Escuela Superior de Inform\u00e1tica de Ciudad Real (Castilla-La Mancha), Universidad de Castilla-La Mancha es un centro universitario que imparte el ciclo completo de Ingenier\u00eda en Inform\u00e1tica: grado, m\u00e1ster y doctorado.\",\"publisher\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/esi.uclm.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\",\"name\":\"Escuela Superior de Inform\u00e1tica de UCLM\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2022\\\/03\\\/LogoESI_cabecera-1.png\",\"contentUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2022\\\/03\\\/LogoESI_cabecera-1.png\",\"width\":460,\"height\":184,\"caption\":\"Escuela Superior de Inform\u00e1tica de UCLM\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Escuela-Superior-de-Informtica-543261809027158\",\"https:\\\/\\\/x.com\\\/esiuclm\",\"https:\\\/\\\/www.instagram.com\\\/esiuclm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/esiuclm\",\"https:\\\/\\\/www.twitch.tv\\\/esiuclm\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/12656631\\\/admin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/person\\\/d9a390095e8beeca5aced92acb17a530\",\"name\":\"esiuclm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"caption\":\"esiuclm\"},\"sameAs\":[\"https:\\\/\\\/esi.uclm.es\"],\"url\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/author\\\/esiadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De las Aulas a la Empresa: Mi Camino desde la Universidad hasta NTT Data - Escuela Superior de Inform\u00e1tica de UCLM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/esi.uclm.es\/index.php\/2024\/03\/05\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\/","og_locale":"es_ES","og_type":"article","og_title":"De las Aulas a la Empresa: Mi Camino desde la Universidad hasta NTT Data - Escuela Superior de Inform\u00e1tica de UCLM","og_description":"Por Ra\u00fal Barba, exalumno y empleado de NTTData Navegando el camino entre la Academia y el Mercado Laboral En la recta final de mi \u00faltimo a\u00f1o de carrera, frente a los \u00faltimos ex\u00e1menes finales y el inicio de mi Trabajo de Fin de Grado, se [&hellip;]","og_url":"https:\/\/esi.uclm.es\/index.php\/2024\/03\/05\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\/","og_site_name":"Escuela Superior de Inform\u00e1tica de UCLM","article_publisher":"https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158","article_published_time":"2024-03-05T10:00:35+00:00","article_modified_time":"2024-03-05T10:01:42+00:00","og_image":[{"width":344,"height":359,"url":"http:\/\/esi.uclm.es\/assets\/uploads\/2024\/03\/rbarba_opinion.png","type":"image\/png"}],"author":"esiuclm","twitter_card":"summary_large_image","twitter_creator":"@esiuclm","twitter_site":"@esiuclm","twitter_misc":{"Escrito por":"esiuclm","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/esi.uclm.es\/index.php\/2024\/03\/05\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\/#article","isPartOf":{"@id":"https:\/\/esi.uclm.es\/index.php\/2024\/03\/05\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\/"},"author":{"name":"esiuclm","@id":"https:\/\/esi.uclm.es\/#\/schema\/person\/d9a390095e8beeca5aced92acb17a530"},"headline":"De las Aulas a la Empresa: Mi Camino desde la Universidad hasta NTT Data","datePublished":"2024-03-05T10:00:35+00:00","dateModified":"2024-03-05T10:01:42+00:00","mainEntityOfPage":{"@id":"https:\/\/esi.uclm.es\/index.php\/2024\/03\/05\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\/"},"wordCount":970,"commentCount":0,"publisher":{"@id":"https:\/\/esi.uclm.es\/#organization"},"image":{"@id":"https:\/\/esi.uclm.es\/index.php\/2024\/03\/05\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\/#primaryimage"},"thumbnailUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2024\/03\/rbarba_opinion.png","articleSection":["Opini\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/esi.uclm.es\/index.php\/2024\/03\/05\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/esi.uclm.es\/index.php\/2024\/03\/05\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\/","url":"https:\/\/esi.uclm.es\/index.php\/2024\/03\/05\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\/","name":"De las Aulas a la Empresa: Mi Camino desde la Universidad hasta NTT Data - Escuela Superior de Inform\u00e1tica de UCLM","isPartOf":{"@id":"https:\/\/esi.uclm.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/esi.uclm.es\/index.php\/2024\/03\/05\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\/#primaryimage"},"image":{"@id":"https:\/\/esi.uclm.es\/index.php\/2024\/03\/05\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\/#primaryimage"},"thumbnailUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2024\/03\/rbarba_opinion.png","datePublished":"2024-03-05T10:00:35+00:00","dateModified":"2024-03-05T10:01:42+00:00","breadcrumb":{"@id":"https:\/\/esi.uclm.es\/index.php\/2024\/03\/05\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/esi.uclm.es\/index.php\/2024\/03\/05\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esi.uclm.es\/index.php\/2024\/03\/05\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\/#primaryimage","url":"https:\/\/esi.uclm.es\/assets\/uploads\/2024\/03\/rbarba_opinion.png","contentUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2024\/03\/rbarba_opinion.png","width":344,"height":359,"caption":"Ra\u00fal Barba"},{"@type":"BreadcrumbList","@id":"https:\/\/esi.uclm.es\/index.php\/2024\/03\/05\/de-las-aulas-a-la-empresa-mi-camino-desde-la-universidad-hasta-ntt-data\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/esi.uclm.es\/"},{"@type":"ListItem","position":2,"name":"De las Aulas a la Empresa: Mi Camino desde la Universidad hasta NTT Data"}]},{"@type":"WebSite","@id":"https:\/\/esi.uclm.es\/#website","url":"https:\/\/esi.uclm.es\/","name":"Escuela Superior de Inform\u00e1tica de UCLM en Ciudad Real, Castilla-La Mancha","description":"La Escuela Superior de Inform\u00e1tica de Ciudad Real (Castilla-La Mancha), Universidad de Castilla-La Mancha es un centro universitario que imparte el ciclo completo de Ingenier\u00eda en Inform\u00e1tica: grado, m\u00e1ster y doctorado.","publisher":{"@id":"https:\/\/esi.uclm.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esi.uclm.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/esi.uclm.es\/#organization","name":"Escuela Superior de Inform\u00e1tica de UCLM","url":"https:\/\/esi.uclm.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esi.uclm.es\/#\/schema\/logo\/image\/","url":"https:\/\/esi.uclm.es\/assets\/uploads\/2022\/03\/LogoESI_cabecera-1.png","contentUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2022\/03\/LogoESI_cabecera-1.png","width":460,"height":184,"caption":"Escuela Superior de Inform\u00e1tica de UCLM"},"image":{"@id":"https:\/\/esi.uclm.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158","https:\/\/x.com\/esiuclm","https:\/\/www.instagram.com\/esiuclm\/","https:\/\/www.youtube.com\/user\/esiuclm","https:\/\/www.twitch.tv\/esiuclm","https:\/\/www.linkedin.com\/company\/12656631\/admin\/"]},{"@type":"Person","@id":"https:\/\/esi.uclm.es\/#\/schema\/person\/d9a390095e8beeca5aced92acb17a530","name":"esiuclm","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","caption":"esiuclm"},"sameAs":["https:\/\/esi.uclm.es"],"url":"https:\/\/esi.uclm.es\/index.php\/author\/esiadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/18166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/comments?post=18166"}],"version-history":[{"count":3,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/18166\/revisions"}],"predecessor-version":[{"id":18170,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/18166\/revisions\/18170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/media\/18167"}],"wp:attachment":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/media?parent=18166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/categories?post=18166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/tags?post=18166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}