{"id":15914,"date":"2023-05-30T16:43:02","date_gmt":"2023-05-30T16:43:02","guid":{"rendered":"https:\/\/esi.uclm.es\/?p=15914"},"modified":"2023-06-08T13:24:42","modified_gmt":"2023-06-08T13:24:42","slug":"pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce","status":"publish","type":"post","link":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/30\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\/","title":{"rendered":"Pelucas Boreal, nuevo proyecto de los estudiantes de COE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hace 12 a\u00f1os, Inma S\u00e1nchez fue diagnosticada con un c\u00e1ncer de mama. Tras superarlo, con una lucha que durar\u00eda 16 meses de quimioterapia y 10 a\u00f1os de pastillas, en 2013, sinti\u00f3 la necesidad de ayudar a otras mujeres que se enfrentaban a esta misma enfermedad y a situaciones que ella ya hab\u00eda vivido, como es la ca\u00edda de pelo. Ella quer\u00eda poner un poco de empat\u00eda en el proceso de recuperaci\u00f3n de esta enfermedad y brindar apoyo emocional basado en su experiencia. Ella aprendi\u00f3, durante la enfermedad, la importancia que ten\u00eda la autoestima y sentirse bien consigo misma para lograr superar la enfermedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inma se form\u00f3 como asesora en est\u00e9tica oncol\u00f3gica y en la recuperaci\u00f3n de la imagen corporal en pr\u00f3tesis de mama, conocimientos que, junto a su experiencia, le permiti\u00f3 fundar en Tomelloso en el a\u00f1o 2013 <a href=\"https:\/\/pelucasboreal.com\/\">Pelucas Boreal<\/a>. Un centro que nac\u00eda con la intenci\u00f3n de ser un lugar \u201cfamiliar\u201d en el que sentirse c\u00f3moda y sobre todo comprendida.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siendo consciente de la importancia que tendr\u00eda internet y la necesidad de tener presencia en la web para que su iniciativa alcanza a la mayor cantidad de mujeres, en 2013 registra el dominio de su tienda, y en 2015 crea su primera p\u00e1gina web. Una p\u00e1gina web cat\u00e1logo en la que se publicitaba Pelucas Boreal, as\u00ed como el cat\u00e1logo de pelucas, postizos, extensiones, turbantes\u2026 as\u00ed como lencer\u00eda mastectom\u00eda que pod\u00eda encontrarse en su tienda f\u00edsica. Esta web estaba enlazada con sus perfiles en las redes sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00edez a\u00f1os m\u00e1s tarde\u2026 los estudiantes de la <a href=\"https:\/\/esi.uclm.es\/\">Escuela Superior de Inform\u00e1tica<\/a> de la <a href=\"https:\/\/www.uclm.es\/\">Universidad de Castilla-La Mancha<\/a>, que cursan la asignatura de Comercio Electr\u00f3nico, conocieron su historia y quisieron ayudarle a dar un paso m\u00e1s en su presencia en la web, dise\u00f1ando y desarrollando una nueva web para su iniciativa. Una nueva web con la que no solo estuviera en la web, sino que tambi\u00e9n le permitiera llevar a cabo sus actividades comerciales en la web: quer\u00edan que pudiera vender sus productos a trav\u00e9s de la web con pago online.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La web de comercio electr\u00f3nico Pelucas Boreal es el resultado de una experiencia de aprendizaje basado en proyectos. En ella, los estudiantes, mientras se enfrentan a los retos que supone el desarrollo del proyecto, aprenden los conocimientos de la asignatura de Comercio Electr\u00f3nico de la intensificaci\u00f3n Tecnolog\u00edas de la Informaci\u00f3n del Grado en Ingenier\u00eda Inform\u00e1tica. Los estudiantes han aprendido a: desarrollar una soluci\u00f3n de comercio electr\u00f3nico, con una apariencia elegante y adaptada a cualquier dispositivo; trabajar el posicionamiento SEO, onpage y offpage; integrar una plataforma de pago online v\u00eda tarjeta de cr\u00e9dito; y tomar datos para realizar anal\u00edtica web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La web ha sido desarrollada por los estudiantes <a href=\"https:\/\/juancaravantes.github.io\/\">Juan Caravantes Algaba<\/a>, <a href=\"https:\/\/mariajesusduenasrecuero.github.io\/portfolio\/\">Mar\u00eda Jes\u00fas Due\u00f1as Recuero<\/a>, <a href=\"https:\/\/sergiogm8.github.io\/\">Sergio Garrido Merino<\/a>, <a href=\"https:\/\/lauramc13.github.io\/\">Laura Morales Caro<\/a> y <a href=\"https:\/\/jesussanchez26.github.io\/\">Jes\u00fas S\u00e1nchez Cambronero-Campos<\/a>, bajo la direcci\u00f3n del profesor <a href=\"https:\/\/www.esi.uclm.es\/www\/jjcastro\/\">Jos\u00e9 Jes\u00fas Castro S\u00e1nchez<\/a>, de modo totalmente altruista e identificados con Inma por su capacidad de lucha, su alegr\u00eda y&nbsp; ganas de vivir y ser feliz. Nuestros estudiantes se llevan un gran aprendizaje profesional y personal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-4-1024x768.png\" alt=\"\" class=\"wp-image-15916\" srcset=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-4-1024x768.png 1024w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-4-300x225.png 300w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-4-768x576.png 768w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-4-1536x1152.png 1536w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-4-800x600.png 800w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-4-1300x975.png 1300w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-4-600x450.png 600w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-4.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Estudiantes que han realizado la web junto al profesor J.J Castro S\u00e1nchez<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"468\" src=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/web_pelucasboreal-1024x468.webp\" alt=\"\" class=\"wp-image-15917\" srcset=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/web_pelucasboreal-1024x468.webp 1024w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/web_pelucasboreal-300x137.webp 300w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/web_pelucasboreal-768x351.webp 768w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/web_pelucasboreal-1536x701.webp 1536w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/web_pelucasboreal-1300x594.webp 1300w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/web_pelucasboreal-600x274.webp 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Proyecto realizado por los estudiantes de comercio electr\u00f3nico en la Escuela Superior de Inform\u00e1tica<\/figcaption><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\"><strong>Interact\u00faa en redes para difundir el proyecto<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<blockquote class=\"twitter-tweet\"><p lang=\"es\" dir=\"ltr\">Saca Pecho por ELLAS<br><br>\ud83c\udf93 Es el \u00faltimo proyecto de nuestros\/as estudiantes de COm\u00e9rcio Electr\u00f3nico (4\u00ba Curso) &#8211; Pelucas Boreal, un lugar \u201cfamiliar\u201d en el que sentirse c\u00f3moda y sobre todo comprendida<br><br>\ud83d\udc49 Conoce el proyecto y su historia: <a href=\"https:\/\/t.co\/IZysa4ycbv\">https:\/\/t.co\/IZysa4ycbv<\/a> <a href=\"https:\/\/t.co\/Zle7BfkHyk\">pic.twitter.com\/Zle7BfkHyk<\/a><\/p>&mdash; ES. Inform\u00e1tica UCLM (@esiuclm) <a href=\"https:\/\/twitter.com\/esiuclm\/status\/1663616139664977924?ref_src=twsrc%5Etfw\">May 30, 2023<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/Cs4L2Kyt1Qz\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/Cs4L2Kyt1Qz\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Ver esta publicaci\u00f3n en Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/Cs4L2Kyt1Qz\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener\">Una publicaci\u00f3n compartida por ESI (@esiuclm)<\/a><\/p><\/div><\/blockquote> <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hace 12 a\u00f1os, Inma S\u00e1nchez fue diagnosticada con un c\u00e1ncer de mama. Tras superarlo, con una lucha que durar\u00eda 16 meses de quimioterapia y 10 a\u00f1os de pastillas, en 2013, sinti\u00f3 la necesidad de ayudar a otras mujeres que se enfrentaban a esta misma enfermedad [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15915,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[622,619],"tags":[],"class_list":["post-15914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-docencia","category-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pelucas Boreal, nuevo proyecto de los estudiantes de COE - Escuela Superior de Inform\u00e1tica de UCLM<\/title>\n<meta name=\"description\" content=\"Hace 12 a\u00f1os, Inma S\u00e1nchez fue diagnosticada con un c\u00e1ncer de mama. Tras superarlo, con una lucha que durar\u00eda 16 meses de quimioterapia y 10 a\u00f1os de pastillas, en 2013, sinti\u00f3 la necesidad de ayudar a otras mujeres que se enfrentaban a esta misma enfermedad y a situaciones que ella ya hab\u00eda vivido, como es la ca\u00edda de pelo. Ella quer\u00eda poner un poco de empat\u00eda en el proceso de recuperaci\u00f3n de esta enfermedad y brindar apoyo emocional basado en su experiencia. Ella aprendi\u00f3, durante la enfermedad, la importancia que ten\u00eda la autoestima y sentirse bien consigo misma para lograr superar la enfermedad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/esi.uclm.es\/index.php\/2023\/05\/30\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pelucas Boreal, nuevo proyecto de los estudiantes de COE - Escuela Superior de Inform\u00e1tica de UCLM\" \/>\n<meta property=\"og:description\" content=\"Hace 12 a\u00f1os, Inma S\u00e1nchez fue diagnosticada con un c\u00e1ncer de mama. Tras superarlo, con una lucha que durar\u00eda 16 meses de quimioterapia y 10 a\u00f1os de pastillas, en 2013, sinti\u00f3 la necesidad de ayudar a otras mujeres que se enfrentaban a esta misma enfermedad y a situaciones que ella ya hab\u00eda vivido, como es la ca\u00edda de pelo. Ella quer\u00eda poner un poco de empat\u00eda en el proceso de recuperaci\u00f3n de esta enfermedad y brindar apoyo emocional basado en su experiencia. Ella aprendi\u00f3, durante la enfermedad, la importancia que ten\u00eda la autoestima y sentirse bien consigo misma para lograr superar la enfermedad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esi.uclm.es\/index.php\/2023\/05\/30\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela Superior de Inform\u00e1tica de UCLM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-30T16:43:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-08T13:24:42+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/pelucas_boreal_WEB.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"867\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"esiuclm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@esiuclm\" \/>\n<meta name=\"twitter:site\" content=\"@esiuclm\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"esiuclm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/30\\\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/30\\\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\\\/\"},\"author\":{\"name\":\"esiuclm\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/person\\\/d9a390095e8beeca5aced92acb17a530\"},\"headline\":\"Pelucas Boreal, nuevo proyecto de los estudiantes de COE\",\"datePublished\":\"2023-05-30T16:43:02+00:00\",\"dateModified\":\"2023-06-08T13:24:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/30\\\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\\\/\"},\"wordCount\":674,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/30\\\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/05\\\/pelucas_boreal_WEB.webp\",\"articleSection\":[\"Docencia\",\"General\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/30\\\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/30\\\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\\\/\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/30\\\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\\\/\",\"name\":\"Pelucas Boreal, nuevo proyecto de los estudiantes de COE - Escuela Superior de Inform\u00e1tica de UCLM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/30\\\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/30\\\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/05\\\/pelucas_boreal_WEB.webp\",\"datePublished\":\"2023-05-30T16:43:02+00:00\",\"dateModified\":\"2023-06-08T13:24:42+00:00\",\"description\":\"Hace 12 a\u00f1os, Inma S\u00e1nchez fue diagnosticada con un c\u00e1ncer de mama. Tras superarlo, con una lucha que durar\u00eda 16 meses de quimioterapia y 10 a\u00f1os de pastillas, en 2013, sinti\u00f3 la necesidad de ayudar a otras mujeres que se enfrentaban a esta misma enfermedad y a situaciones que ella ya hab\u00eda vivido, como es la ca\u00edda de pelo. Ella quer\u00eda poner un poco de empat\u00eda en el proceso de recuperaci\u00f3n de esta enfermedad y brindar apoyo emocional basado en su experiencia. Ella aprendi\u00f3, durante la enfermedad, la importancia que ten\u00eda la autoestima y sentirse bien consigo misma para lograr superar la enfermedad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/30\\\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/30\\\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/30\\\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\\\/#primaryimage\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/05\\\/pelucas_boreal_WEB.webp\",\"contentUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/05\\\/pelucas_boreal_WEB.webp\",\"width\":1300,\"height\":867,\"caption\":\"Lazo Rosa, cancer de mama\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/30\\\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/esi.uclm.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pelucas Boreal, nuevo proyecto de los estudiantes de COE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#website\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/\",\"name\":\"Escuela Superior de Inform\u00e1tica de UCLM en Ciudad Real, Castilla-La Mancha\",\"description\":\"La Escuela Superior de Inform\u00e1tica de Ciudad Real (Castilla-La Mancha), Universidad de Castilla-La Mancha es un centro universitario que imparte el ciclo completo de Ingenier\u00eda en Inform\u00e1tica: grado, m\u00e1ster y doctorado.\",\"publisher\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/esi.uclm.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\",\"name\":\"Escuela Superior de Inform\u00e1tica de UCLM\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2022\\\/03\\\/LogoESI_cabecera-1.png\",\"contentUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2022\\\/03\\\/LogoESI_cabecera-1.png\",\"width\":460,\"height\":184,\"caption\":\"Escuela Superior de Inform\u00e1tica de UCLM\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Escuela-Superior-de-Informtica-543261809027158\",\"https:\\\/\\\/x.com\\\/esiuclm\",\"https:\\\/\\\/www.instagram.com\\\/esiuclm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/esiuclm\",\"https:\\\/\\\/www.twitch.tv\\\/esiuclm\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/12656631\\\/admin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/person\\\/d9a390095e8beeca5aced92acb17a530\",\"name\":\"esiuclm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"caption\":\"esiuclm\"},\"sameAs\":[\"https:\\\/\\\/esi.uclm.es\"],\"url\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/author\\\/esiadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pelucas Boreal, nuevo proyecto de los estudiantes de COE - Escuela Superior de Inform\u00e1tica de UCLM","description":"Hace 12 a\u00f1os, Inma S\u00e1nchez fue diagnosticada con un c\u00e1ncer de mama. Tras superarlo, con una lucha que durar\u00eda 16 meses de quimioterapia y 10 a\u00f1os de pastillas, en 2013, sinti\u00f3 la necesidad de ayudar a otras mujeres que se enfrentaban a esta misma enfermedad y a situaciones que ella ya hab\u00eda vivido, como es la ca\u00edda de pelo. Ella quer\u00eda poner un poco de empat\u00eda en el proceso de recuperaci\u00f3n de esta enfermedad y brindar apoyo emocional basado en su experiencia. Ella aprendi\u00f3, durante la enfermedad, la importancia que ten\u00eda la autoestima y sentirse bien consigo misma para lograr superar la enfermedad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/30\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\/","og_locale":"es_ES","og_type":"article","og_title":"Pelucas Boreal, nuevo proyecto de los estudiantes de COE - Escuela Superior de Inform\u00e1tica de UCLM","og_description":"Hace 12 a\u00f1os, Inma S\u00e1nchez fue diagnosticada con un c\u00e1ncer de mama. Tras superarlo, con una lucha que durar\u00eda 16 meses de quimioterapia y 10 a\u00f1os de pastillas, en 2013, sinti\u00f3 la necesidad de ayudar a otras mujeres que se enfrentaban a esta misma enfermedad y a situaciones que ella ya hab\u00eda vivido, como es la ca\u00edda de pelo. Ella quer\u00eda poner un poco de empat\u00eda en el proceso de recuperaci\u00f3n de esta enfermedad y brindar apoyo emocional basado en su experiencia. Ella aprendi\u00f3, durante la enfermedad, la importancia que ten\u00eda la autoestima y sentirse bien consigo misma para lograr superar la enfermedad.","og_url":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/30\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\/","og_site_name":"Escuela Superior de Inform\u00e1tica de UCLM","article_publisher":"https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158","article_published_time":"2023-05-30T16:43:02+00:00","article_modified_time":"2023-06-08T13:24:42+00:00","og_image":[{"width":1300,"height":867,"url":"http:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/pelucas_boreal_WEB.webp","type":"image\/webp"}],"author":"esiuclm","twitter_card":"summary_large_image","twitter_creator":"@esiuclm","twitter_site":"@esiuclm","twitter_misc":{"Escrito por":"esiuclm","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/30\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\/#article","isPartOf":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/30\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\/"},"author":{"name":"esiuclm","@id":"https:\/\/esi.uclm.es\/#\/schema\/person\/d9a390095e8beeca5aced92acb17a530"},"headline":"Pelucas Boreal, nuevo proyecto de los estudiantes de COE","datePublished":"2023-05-30T16:43:02+00:00","dateModified":"2023-06-08T13:24:42+00:00","mainEntityOfPage":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/30\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\/"},"wordCount":674,"commentCount":0,"publisher":{"@id":"https:\/\/esi.uclm.es\/#organization"},"image":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/30\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\/#primaryimage"},"thumbnailUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/pelucas_boreal_WEB.webp","articleSection":["Docencia","General"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/esi.uclm.es\/index.php\/2023\/05\/30\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/30\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\/","url":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/30\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\/","name":"Pelucas Boreal, nuevo proyecto de los estudiantes de COE - Escuela Superior de Inform\u00e1tica de UCLM","isPartOf":{"@id":"https:\/\/esi.uclm.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/30\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\/#primaryimage"},"image":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/30\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\/#primaryimage"},"thumbnailUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/pelucas_boreal_WEB.webp","datePublished":"2023-05-30T16:43:02+00:00","dateModified":"2023-06-08T13:24:42+00:00","description":"Hace 12 a\u00f1os, Inma S\u00e1nchez fue diagnosticada con un c\u00e1ncer de mama. Tras superarlo, con una lucha que durar\u00eda 16 meses de quimioterapia y 10 a\u00f1os de pastillas, en 2013, sinti\u00f3 la necesidad de ayudar a otras mujeres que se enfrentaban a esta misma enfermedad y a situaciones que ella ya hab\u00eda vivido, como es la ca\u00edda de pelo. Ella quer\u00eda poner un poco de empat\u00eda en el proceso de recuperaci\u00f3n de esta enfermedad y brindar apoyo emocional basado en su experiencia. Ella aprendi\u00f3, durante la enfermedad, la importancia que ten\u00eda la autoestima y sentirse bien consigo misma para lograr superar la enfermedad.","breadcrumb":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/30\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/esi.uclm.es\/index.php\/2023\/05\/30\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/30\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\/#primaryimage","url":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/pelucas_boreal_WEB.webp","contentUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/pelucas_boreal_WEB.webp","width":1300,"height":867,"caption":"Lazo Rosa, cancer de mama"},{"@type":"BreadcrumbList","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/30\/pelucas-boreal-nuevo-proyecto-de-los-estudiantes-de-ce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/esi.uclm.es\/"},{"@type":"ListItem","position":2,"name":"Pelucas Boreal, nuevo proyecto de los estudiantes de COE"}]},{"@type":"WebSite","@id":"https:\/\/esi.uclm.es\/#website","url":"https:\/\/esi.uclm.es\/","name":"Escuela Superior de Inform\u00e1tica de UCLM en Ciudad Real, Castilla-La Mancha","description":"La Escuela Superior de Inform\u00e1tica de Ciudad Real (Castilla-La Mancha), Universidad de Castilla-La Mancha es un centro universitario que imparte el ciclo completo de Ingenier\u00eda en Inform\u00e1tica: grado, m\u00e1ster y doctorado.","publisher":{"@id":"https:\/\/esi.uclm.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esi.uclm.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/esi.uclm.es\/#organization","name":"Escuela Superior de Inform\u00e1tica de UCLM","url":"https:\/\/esi.uclm.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esi.uclm.es\/#\/schema\/logo\/image\/","url":"https:\/\/esi.uclm.es\/assets\/uploads\/2022\/03\/LogoESI_cabecera-1.png","contentUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2022\/03\/LogoESI_cabecera-1.png","width":460,"height":184,"caption":"Escuela Superior de Inform\u00e1tica de UCLM"},"image":{"@id":"https:\/\/esi.uclm.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158","https:\/\/x.com\/esiuclm","https:\/\/www.instagram.com\/esiuclm\/","https:\/\/www.youtube.com\/user\/esiuclm","https:\/\/www.twitch.tv\/esiuclm","https:\/\/www.linkedin.com\/company\/12656631\/admin\/"]},{"@type":"Person","@id":"https:\/\/esi.uclm.es\/#\/schema\/person\/d9a390095e8beeca5aced92acb17a530","name":"esiuclm","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","caption":"esiuclm"},"sameAs":["https:\/\/esi.uclm.es"],"url":"https:\/\/esi.uclm.es\/index.php\/author\/esiadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/15914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/comments?post=15914"}],"version-history":[{"count":5,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/15914\/revisions"}],"predecessor-version":[{"id":15931,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/15914\/revisions\/15931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/media\/15915"}],"wp:attachment":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/media?parent=15914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/categories?post=15914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/tags?post=15914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}