{"id":15826,"date":"2023-05-21T05:38:52","date_gmt":"2023-05-21T05:38:52","guid":{"rendered":"https:\/\/esi.uclm.es\/?p=15826"},"modified":"2023-05-21T20:13:48","modified_gmt":"2023-05-21T20:13:48","slug":"homo-computationalis","status":"publish","type":"post","link":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/21\/homo-computationalis\/","title":{"rendered":"Homo Computationalis"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Por <em>Ricardo Garc\u00eda<\/em> (Catedr\u00e1tico de Universidad)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los viajes m\u00e1s heroicos de la navegaci\u00f3n corri\u00f3 a cargo de Ernest Shackleton y su tripulaci\u00f3n. Su barco, <em>Endurence,<\/em> se vio atrapado por los hielos de la Ant\u00e1rtida, que lo colaps\u00f3, dejando a los marineros encima de los hielos. Shackleton condujo a su tripulaci\u00f3n a la isla deshabitada Elefante y \u00e9l con otros cinco marineros har\u00edan un viaje de casi 1600 kil\u00f3metros en busca de auxilio. La traves\u00eda dur\u00f3 16 d\u00edas hasta alcanzar la estaci\u00f3n ballenera de la isla de Georgia del Sur. La navegaci\u00f3n se realizaba mediante sextante y las malas condiciones meteorol\u00f3gicas solo le permiti\u00f3 al Capit\u00e1n realizar tres mediciones, pero su precisi\u00f3n en los c\u00e1lculos le condujo a la isla Elefante.&nbsp; La historia de la mariner\u00eda est\u00e1 plagada de historias con desigual desenlace, donde el c\u00e1lculo err\u00f3neo, como del radio de la Tierra, comprometi\u00f3 la supervivencia de sus tripulantes.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/barco_expedicion_logo.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/barco_expedicion_logo-1024x512.webp\" alt=\"\" class=\"wp-image-15865\" srcset=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/barco_expedicion_logo-1024x512.webp 1024w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/barco_expedicion_logo-300x150.webp 300w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/barco_expedicion_logo-768x384.webp 768w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/barco_expedicion_logo-1300x650.webp 1300w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/barco_expedicion_logo-1100x550.webp 1100w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/barco_expedicion_logo-600x300.webp 600w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/barco_expedicion_logo.webp 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Ernest Shackleton y su tripulaci\u00f3n en su barco, <em>Endurence<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">La importancia de la computaci\u00f3n en la historia de la humanidad no se puede limitar a microhistorias como la anterior, sino que ha ocupado un papel central y lo seguir\u00e1 haciendo en el devenir humano. Estoy pensando en un concepto amplio de capacidad computacional y me viene a la cabeza el t\u00edtulo del libro de <a href=\"https:\/\/www.amazon.es\/Cerebros-m%C3%A1quinas-matem%C3%A1ticas-Alianza-Universidad\/dp\/8420621587\">M. Arbib (1981) <em>Cerebros, m\u00e1quinas y matem\u00e1ticas<\/em><\/a>. Su t\u00edtulo me resulta adecuado para fijar las coordenadas donde situar el concepto, donde <em>la inteligencia artificial<\/em> es una parte de esta capacidad.<\/p>\n\n\n\n<div style=\"height:34px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">La ciencia nos permite entender el mundo y la tecnolog\u00eda vivir en el mundo. La capacidad computacional es una habilidad transversal y esencial en los contextos cient\u00edficos y tecnol\u00f3gicos. &nbsp;Como sociedad debemos priorizarla por varios motivos.&nbsp;<\/p>\n<\/blockquote>\n\n\n\n<div style=\"height:47px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/capacidad_computacional2_logo.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/capacidad_computacional2_logo-1024x512.webp\" alt=\"\" class=\"wp-image-15866\" srcset=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/capacidad_computacional2_logo-1024x512.webp 1024w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/capacidad_computacional2_logo-300x150.webp 300w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/capacidad_computacional2_logo-768x384.webp 768w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/capacidad_computacional2_logo-1300x650.webp 1300w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/capacidad_computacional2_logo-1100x550.webp 1100w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/capacidad_computacional2_logo-600x300.webp 600w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/capacidad_computacional2_logo.webp 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Crecimiento de la capacidad computacional<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">En un mundo finito, como el nuestro, es inviable una econom\u00eda creciente. Donella H. Meadows y otros (1972) constataron este hecho en su informe <em><a href=\"https:\/\/es.wikipedia.org\/wiki\/Los_l%C3%ADmites_del_crecimiento\">Los l\u00edmites del crecimiento<\/a><\/em> realizado por encargo del Club de Roma. Existe una ilusi\u00f3n que nos hace creer que los infinitos problemas ser\u00e1n resueltos por una ciencia y tecnolog\u00eda que consigue cada d\u00eda \u00e9xitos m\u00e1s notables e incre\u00edbles. &nbsp;Estas ideas tambi\u00e9n son promovidas por lobbies y requiere de un pensamiento cr\u00edtico que pueda evaluar y tomar sus propias conclusiones. Esto es una de las cualidades de la capacidad computacional. Por ejemplo, si queremos cuestionar que los cambios tecnol\u00f3gicos van a resolver los problemas derivados del crecimiento podemos analizar un ejemplo concreto. En la actualidad hay una creencia que se va a producir un cambio de modelo energ\u00e9tico en la automoci\u00f3n, siendo el coche el\u00e9ctrico el reemplazamiento natural a los motores de combusti\u00f3n. Si se dedicase toda la producci\u00f3n mundial de litio a la construcci\u00f3n de bater\u00edas para coches el\u00e9ctricos, dejando desatendidos m\u00f3viles, <em>tablets<\/em>, etc. se producir\u00eda menos de 18 millones de veh\u00edculos. La producci\u00f3n mundial en el 2022 fue de 85 millones de veh\u00edculos en total. El corolario es que deber\u00edamos producir m\u00e1s de cuatro veces m\u00e1s litio para mantener las condiciones actuales. La cuantificaci\u00f3n desacopla el problema de aspectos de creencias y apriorismos, y hace luz en la respuesta. &nbsp;Es una herramienta esencial para mejorar <strong>la capacidad cr\u00edtica.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Existen m\u00faltiples argumentos para fijar un escenario futuro donde la escala de la econom\u00eda es considerablemente mucho menor que la actual (\u00bf40% quiz\u00e1s?) e independientemente de las decisiones pol\u00edticas medioambientales que se pudieran tomar. En el proceso de convergencia se van a producir choques con los l\u00edmites de la propia Tierra y <strong>dar una respuesta acertada de cu\u00e1nto, d\u00f3nde, cu\u00e1ndo o c\u00f3mo<\/strong> vuelve a ser esencial para la propia <strong>supervivencia<\/strong>. Es una nueva traves\u00eda en el <em>Endurence<\/em> y acertar en las decisiones, para no volver a quedar atrapado en el hielo o poder llegar a Georgia del Sur, nos va a demandar la mejor de las capacidades computacionales<strong>.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo dotarnos como sociedad de esta capacidad computacional? La respuesta var\u00eda de unos pa\u00edses a otros. EEUU es capaz de atraer el talento de todo el globo y disponer del grueso de los recursos disponibles. China lo f\u00eda a su propio volumen mientras que la UE debe potenciar y retener todo su talento. Adem\u00e1s, no est\u00e1 garantizada la cooperaci\u00f3n de los agentes que compiten por los recursos. Por ejemplo, si EEUU construye un ordenador cu\u00e1ntico jam\u00e1s se lo vender\u00eda a China (ni a la UE), de hecho, todos los desarrollos cient\u00edficos actuales que posibiliten su construcci\u00f3n llevan aparejado las mismas medidas de seguridad que si se tratara de tecnolog\u00eda militar. Tambi\u00e9n var\u00edan los l\u00edmites en esta carrera, por ejemplo, cuestiones \u00e9ticas en el desarrollo de la inteligencia artificial son menos discutidas en China e incluso en EEUU que las planteadas en la UE (<a href=\"https:\/\/www.europarl.europa.eu\/committees\/en\/imco\/home\/highlights#:~:text=On%2026%20April%202023%2C%20IMCO,of%2022%2F23%20May%202023.\"><em>Committee on the Internal Market and Consumer Protection<\/em>, 2023<\/a>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si nos situamos en una escala local o regional, los grados de libertad del espacio de soluciones para incrementar nuestra capacidad computacional se reduce dr\u00e1sticamente. Adem\u00e1s, hay que lidiar que en los m\u00e1rgenes de los m\u00e1rgenes estas cuestiones parecen no apelarnos. Descifrar la estructura de una prote\u00edna o hacer los c\u00e1lculos necesarios en nanotecnolog\u00eda se vuelve cosas de los otros, juegos caros e in\u00fatiles para nuestros problemas diarios. Algunas acciones plausibles son:<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li>Hay que entender el funcionamiento disruptivo de los avances cient\u00edficos y tecnol\u00f3gicos. Por ejemplo, en la investigaci\u00f3n farmacol\u00f3gica solo un porcentaje residual de los principios activos ensayados resultan de inter\u00e9s pr\u00e1ctico. Pero pese a eso, el retorno de esa fracci\u00f3n infinitesimal compensa toda la inversi\u00f3n. Esta misma situaci\u00f3n est\u00e1 presente en la ciencia y en la tecnolog\u00eda en general. Hay que asumir esta regla de funcionamiento y dotar una financiaci\u00f3n amplia a la investigaci\u00f3n en esta materia. Adem\u00e1s, desvincularla de r\u00e9ditos inmediatos o extremadamente finalistas.<\/li>\n\n\n\n<li>El 1.4% de la poblaci\u00f3n activa se dedica a la agricultura en la UE y esta actividad econ\u00f3mica genera aproximadamente el 1.5% del PIB, sin embargo, por cuestiones hist\u00f3ricas y estrat\u00e9gicas se le dedica un 40% del presupuesto de la UE a este sector. Se ha pasado del 60% del presupuesto al 40% sin un impacto catastr\u00f3fico, como una suerte de reemplazo de riego por inundaci\u00f3n por riego por goteo. De la misma manera se debe entender como estrat\u00e9gica la capacidad computacional y financiar la creaci\u00f3n de empleos en estos sectores para que ning\u00fan talento en el territorio de la UE quede malogrado por falta de riego.<\/li>\n\n\n\n<li>La formaci\u00f3n es una palanca esencial para el desarrollo de esta capacidad.&nbsp; En el nivel de educaci\u00f3n secundaria la inclusi\u00f3n de una asignatura de programaci\u00f3n en bachillerato es necesaria. Adem\u00e1s, los programas de matem\u00e1ticas son muy extensos y se cubren superficialmente, desarroll\u00e1ndose marcados por la necesidad de aprobar ex\u00e1menes y dejando en un segundo plano el desarrollo de capacidades matem\u00e1ticas. En el nivel universitario se produce un desequilibrio en la formaci\u00f3n t\u00e9cnica entre la parte tecnolog\u00eda y sus fundamentos. Se prima generar una fuerza de trabajo para la industria frente al desarrollo del conocimiento.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">El desarrollo de la capacidad de c\u00f3mputo dar\u00e1 soluciones a algunos de los problemas inabordables hasta la fecha. Se dise\u00f1ar\u00e1n materiales o f\u00e1rmacos a escalas inimaginablemente peque\u00f1as, o se plantear\u00e1n problemas ingenieriles a escala planetaria (geoingenier\u00eda) pero el <em>elefante en el sal\u00f3n<\/em> es la m\u00e1quina con inteligencia artificial general (AGI, en su acr\u00f3nimo en lengua inglesa).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.frontiersin.org\/articles\/10.3389\/fevo.2021.806283\/full\">Roli, Jaeger y Kauffman (2022)<\/a> argumentan que la AGI no es realizable porque los marcos algor\u00edtmicos tienen un sistema cerrado de posibilidades y los algoritmos no pueden percibir nuevos marcos y transcender de los propios. La inteligencia humana es como una cadena de conjuntos&nbsp; A1\u2286A2\u2286\u2026. los cuales albergan paradigmas de pensamientos que son accesibles de uno a otro por su contenci\u00f3n, mientras que en los marcos algor\u00edtmicos existe una clausura, por amplia que esta sea, A1\u2286A2\u2286\u2026.\u2286Ak, que cierra el conjunto de posibilidades. La AGI equivale a plantearse si la inteligencia humana es computable, en dicho caso la <em>M\u00e1quina de Turing Universal<\/em> podr\u00eda implementarla. Sabemos que existen problemas, como el <em>problema de la parada<\/em>, que no tiene un algoritmo para resolverlo. La AGI puede estar en la misma situaci\u00f3n y ser una entelequia, pero si no lo fuese y compar\u00e1ramos el reto que hubiera sido para el Imperio Romano llegar a la Luna con el reto de conseguir la AGI para los actuales imperios (EEUU o China) pudieran parecer de una dificultad del mismo orden de magnitud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si lleg\u00e1semos a estas lunas donde las m\u00e1quinas pensaran, nuestro ser de homos sapiens sapiens ser\u00eda consciente que pensar no es m\u00e1s que calcular, que la simbiosis con las m\u00e1quinas continua la evoluci\u00f3n humana y quiz\u00e1s t\u00e9rminos como el de <strong>homo computationalis<\/strong> fuese m\u00e1s adecuado para esos nuevos tiempos.<\/p>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/montaje_evolucion_TV3.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"564\" src=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/montaje_evolucion_TV3-1024x564.webp\" alt=\"\" class=\"wp-image-15859\" srcset=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/montaje_evolucion_TV3-1024x564.webp 1024w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/montaje_evolucion_TV3-300x165.webp 300w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/montaje_evolucion_TV3-768x423.webp 768w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/montaje_evolucion_TV3-1536x846.webp 1536w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/montaje_evolucion_TV3-1300x716.webp 1300w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/montaje_evolucion_TV3-600x331.webp 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Bibliograf\u00eda<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li>M. Arbib (1981) <em>Cerebros, m\u00e1quinas y matem\u00e1tica<\/em>s, Alianza Universidad.<\/li>\n\n\n\n<li>Committee on the Internal Market and Consumer Protection (2023). AI Act: a step closer to the first rules on Artificial Intelligence. https:\/\/www.europarl.europa.eu\/news\/es\/press-room\/20230505IPR84904\/ai-act-a-step-closer-to-the-first-rules-on-artificial-intelligence<\/li>\n\n\n\n<li>&nbsp;D. Meadows y otros (1972) <em>Los L\u00edmites del crecimiento: informe al Club de Roma sobre el predicamento de la humanidad<\/em>, Fondo de Cultura Econ\u00f3mica.<\/li>\n\n\n\n<li>&nbsp;A. Roli, J. Jaeger y S, A. Kauffman (2022). How Organisms Come to Know the World: Fundamental Limits on Artificial General Intelligence. Front. Ecol. Evol., 28 , Sec. Models in Ecology and Evolution &nbsp;Volume 9 &#8211; 2021 | <a href=\"https:\/\/doi.org\/10.3389\/fevo.2021.806283\">https:\/\/doi.org\/10.3389\/fevo.2021.806283<\/a><\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Art\u00edculos de Opini\u00f3n de la ESI<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/esi.uclm.es\/index.php\/category\/opinion\/\">[+] Otros art\u00edculos de opini\u00f3n<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Interact\u00faa en redes<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<blockquote class=\"twitter-tweet\"><p lang=\"es\" dir=\"ltr\">\ud83e\udd14\u00bfC\u00f3mo la capacidad computacional puede definir nuestra <a href=\"https:\/\/twitter.com\/hashtag\/historia?src=hash&amp;ref_src=twsrc%5Etfw\">#historia<\/a> y <a href=\"https:\/\/twitter.com\/hashtag\/futuro?src=hash&amp;ref_src=twsrc%5Etfw\">#futuro<\/a> como especie en un mundo con recursos limitados \ud83c\udf3f\ud83c\udf0e? Desc\u00fabrelo en &#39;Homo Computationalis&#39; un brillante art\u00edculo de opini\u00f3n de Ricardo Garc\u00eda, catedr\u00e1tico de <a href=\"https:\/\/twitter.com\/uclm_es?ref_src=twsrc%5Etfw\">@uclm_es<\/a> en <a href=\"https:\/\/twitter.com\/hashtag\/ESI?src=hash&amp;ref_src=twsrc%5Etfw\">#ESI<\/a> <br><br>\ud83d\udc49 <a href=\"https:\/\/t.co\/lkWmIpUF9y\">https:\/\/t.co\/lkWmIpUF9y<\/a> <a href=\"https:\/\/t.co\/EJEcFLbpCa\">pic.twitter.com\/EJEcFLbpCa<\/a><\/p>&mdash; ES. Inform\u00e1tica UCLM (@esiuclm) <a href=\"https:\/\/twitter.com\/esiuclm\/status\/1660184020288782336?ref_src=twsrc%5Etfw\">May 21, 2023<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CsfyQ5KtnVx\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CsfyQ5KtnVx\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Ver esta publicaci\u00f3n en Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CsfyQ5KtnVx\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener\">Una publicaci\u00f3n compartida por ESI (@esiuclm)<\/a><\/p><\/div><\/blockquote> <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Ricardo Garc\u00eda (Catedr\u00e1tico de Universidad) Uno de los viajes m\u00e1s heroicos de la navegaci\u00f3n corri\u00f3 a cargo de Ernest Shackleton y su tripulaci\u00f3n. Su barco, Endurence, se vio atrapado por los hielos de la Ant\u00e1rtida, que lo colaps\u00f3, dejando a los marineros encima de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15831,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[680],"tags":[],"class_list":["post-15826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Homo Computationalis - Escuela Superior de Inform\u00e1tica de UCLM<\/title>\n<meta name=\"description\" content=\"\u00bfC\u00f3mo la capacidad computacional puede definir nuestra historia y futuro como especie? Desc\u00fabrelo en nuestro nuevo art\u00edculo &#039;Homo Computationalis&#039;. \u00a1Un viaje desde Shackleton en la Ant\u00e1rtida hasta la inteligencia artificial general!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/esi.uclm.es\/index.php\/2023\/05\/21\/homo-computationalis\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Homo Computationalis - Escuela Superior de Inform\u00e1tica de UCLM\" \/>\n<meta property=\"og:description\" content=\"\u00bfC\u00f3mo la capacidad computacional puede definir nuestra historia y futuro como especie? Desc\u00fabrelo en nuestro nuevo art\u00edculo &#039;Homo Computationalis&#039;. \u00a1Un viaje desde Shackleton en la Ant\u00e1rtida hasta la inteligencia artificial general!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esi.uclm.es\/index.php\/2023\/05\/21\/homo-computationalis\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela Superior de Inform\u00e1tica de UCLM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-21T05:38:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-21T20:13:48+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/Ricardo_author.png\" \/>\n\t<meta property=\"og:image:width\" content=\"344\" \/>\n\t<meta property=\"og:image:height\" content=\"359\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"esiuclm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@esiuclm\" \/>\n<meta name=\"twitter:site\" content=\"@esiuclm\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"esiuclm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/21\\\/homo-computationalis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/21\\\/homo-computationalis\\\/\"},\"author\":{\"name\":\"esiuclm\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/person\\\/d9a390095e8beeca5aced92acb17a530\"},\"headline\":\"Homo Computationalis\",\"datePublished\":\"2023-05-21T05:38:52+00:00\",\"dateModified\":\"2023-05-21T20:13:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/21\\\/homo-computationalis\\\/\"},\"wordCount\":1761,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/21\\\/homo-computationalis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/05\\\/Ricardo_author.png\",\"articleSection\":[\"Opini\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/21\\\/homo-computationalis\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/21\\\/homo-computationalis\\\/\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/21\\\/homo-computationalis\\\/\",\"name\":\"Homo Computationalis - Escuela Superior de Inform\u00e1tica de UCLM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/21\\\/homo-computationalis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/21\\\/homo-computationalis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/05\\\/Ricardo_author.png\",\"datePublished\":\"2023-05-21T05:38:52+00:00\",\"dateModified\":\"2023-05-21T20:13:48+00:00\",\"description\":\"\u00bfC\u00f3mo la capacidad computacional puede definir nuestra historia y futuro como especie? Desc\u00fabrelo en nuestro nuevo art\u00edculo 'Homo Computationalis'. \u00a1Un viaje desde Shackleton en la Ant\u00e1rtida hasta la inteligencia artificial general!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/21\\\/homo-computationalis\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/21\\\/homo-computationalis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/21\\\/homo-computationalis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/05\\\/Ricardo_author.png\",\"contentUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/05\\\/Ricardo_author.png\",\"width\":344,\"height\":359,\"caption\":\"Ricardo garc\u00eda R\u00f3denas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/21\\\/homo-computationalis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/esi.uclm.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homo Computationalis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#website\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/\",\"name\":\"Escuela Superior de Inform\u00e1tica de UCLM en Ciudad Real, Castilla-La Mancha\",\"description\":\"La Escuela Superior de Inform\u00e1tica de Ciudad Real (Castilla-La Mancha), Universidad de Castilla-La Mancha es un centro universitario que imparte el ciclo completo de Ingenier\u00eda en Inform\u00e1tica: grado, m\u00e1ster y doctorado.\",\"publisher\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/esi.uclm.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\",\"name\":\"Escuela Superior de Inform\u00e1tica de UCLM\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2022\\\/03\\\/LogoESI_cabecera-1.png\",\"contentUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2022\\\/03\\\/LogoESI_cabecera-1.png\",\"width\":460,\"height\":184,\"caption\":\"Escuela Superior de Inform\u00e1tica de UCLM\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Escuela-Superior-de-Informtica-543261809027158\",\"https:\\\/\\\/x.com\\\/esiuclm\",\"https:\\\/\\\/www.instagram.com\\\/esiuclm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/esiuclm\",\"https:\\\/\\\/www.twitch.tv\\\/esiuclm\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/12656631\\\/admin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/person\\\/d9a390095e8beeca5aced92acb17a530\",\"name\":\"esiuclm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"caption\":\"esiuclm\"},\"sameAs\":[\"https:\\\/\\\/esi.uclm.es\"],\"url\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/author\\\/esiadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Homo Computationalis - Escuela Superior de Inform\u00e1tica de UCLM","description":"\u00bfC\u00f3mo la capacidad computacional puede definir nuestra historia y futuro como especie? Desc\u00fabrelo en nuestro nuevo art\u00edculo 'Homo Computationalis'. \u00a1Un viaje desde Shackleton en la Ant\u00e1rtida hasta la inteligencia artificial general!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/21\/homo-computationalis\/","og_locale":"es_ES","og_type":"article","og_title":"Homo Computationalis - Escuela Superior de Inform\u00e1tica de UCLM","og_description":"\u00bfC\u00f3mo la capacidad computacional puede definir nuestra historia y futuro como especie? Desc\u00fabrelo en nuestro nuevo art\u00edculo 'Homo Computationalis'. \u00a1Un viaje desde Shackleton en la Ant\u00e1rtida hasta la inteligencia artificial general!","og_url":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/21\/homo-computationalis\/","og_site_name":"Escuela Superior de Inform\u00e1tica de UCLM","article_publisher":"https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158","article_published_time":"2023-05-21T05:38:52+00:00","article_modified_time":"2023-05-21T20:13:48+00:00","og_image":[{"width":344,"height":359,"url":"http:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/Ricardo_author.png","type":"image\/png"}],"author":"esiuclm","twitter_card":"summary_large_image","twitter_creator":"@esiuclm","twitter_site":"@esiuclm","twitter_misc":{"Escrito por":"esiuclm","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/21\/homo-computationalis\/#article","isPartOf":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/21\/homo-computationalis\/"},"author":{"name":"esiuclm","@id":"https:\/\/esi.uclm.es\/#\/schema\/person\/d9a390095e8beeca5aced92acb17a530"},"headline":"Homo Computationalis","datePublished":"2023-05-21T05:38:52+00:00","dateModified":"2023-05-21T20:13:48+00:00","mainEntityOfPage":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/21\/homo-computationalis\/"},"wordCount":1761,"commentCount":0,"publisher":{"@id":"https:\/\/esi.uclm.es\/#organization"},"image":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/21\/homo-computationalis\/#primaryimage"},"thumbnailUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/Ricardo_author.png","articleSection":["Opini\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/esi.uclm.es\/index.php\/2023\/05\/21\/homo-computationalis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/21\/homo-computationalis\/","url":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/21\/homo-computationalis\/","name":"Homo Computationalis - Escuela Superior de Inform\u00e1tica de UCLM","isPartOf":{"@id":"https:\/\/esi.uclm.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/21\/homo-computationalis\/#primaryimage"},"image":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/21\/homo-computationalis\/#primaryimage"},"thumbnailUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/Ricardo_author.png","datePublished":"2023-05-21T05:38:52+00:00","dateModified":"2023-05-21T20:13:48+00:00","description":"\u00bfC\u00f3mo la capacidad computacional puede definir nuestra historia y futuro como especie? Desc\u00fabrelo en nuestro nuevo art\u00edculo 'Homo Computationalis'. \u00a1Un viaje desde Shackleton en la Ant\u00e1rtida hasta la inteligencia artificial general!","breadcrumb":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/21\/homo-computationalis\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/esi.uclm.es\/index.php\/2023\/05\/21\/homo-computationalis\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/21\/homo-computationalis\/#primaryimage","url":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/Ricardo_author.png","contentUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/Ricardo_author.png","width":344,"height":359,"caption":"Ricardo garc\u00eda R\u00f3denas"},{"@type":"BreadcrumbList","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/21\/homo-computationalis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/esi.uclm.es\/"},{"@type":"ListItem","position":2,"name":"Homo Computationalis"}]},{"@type":"WebSite","@id":"https:\/\/esi.uclm.es\/#website","url":"https:\/\/esi.uclm.es\/","name":"Escuela Superior de Inform\u00e1tica de UCLM en Ciudad Real, Castilla-La Mancha","description":"La Escuela Superior de Inform\u00e1tica de Ciudad Real (Castilla-La Mancha), Universidad de Castilla-La Mancha es un centro universitario que imparte el ciclo completo de Ingenier\u00eda en Inform\u00e1tica: grado, m\u00e1ster y doctorado.","publisher":{"@id":"https:\/\/esi.uclm.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esi.uclm.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/esi.uclm.es\/#organization","name":"Escuela Superior de Inform\u00e1tica de UCLM","url":"https:\/\/esi.uclm.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esi.uclm.es\/#\/schema\/logo\/image\/","url":"https:\/\/esi.uclm.es\/assets\/uploads\/2022\/03\/LogoESI_cabecera-1.png","contentUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2022\/03\/LogoESI_cabecera-1.png","width":460,"height":184,"caption":"Escuela Superior de Inform\u00e1tica de UCLM"},"image":{"@id":"https:\/\/esi.uclm.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158","https:\/\/x.com\/esiuclm","https:\/\/www.instagram.com\/esiuclm\/","https:\/\/www.youtube.com\/user\/esiuclm","https:\/\/www.twitch.tv\/esiuclm","https:\/\/www.linkedin.com\/company\/12656631\/admin\/"]},{"@type":"Person","@id":"https:\/\/esi.uclm.es\/#\/schema\/person\/d9a390095e8beeca5aced92acb17a530","name":"esiuclm","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","caption":"esiuclm"},"sameAs":["https:\/\/esi.uclm.es"],"url":"https:\/\/esi.uclm.es\/index.php\/author\/esiadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/15826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/comments?post=15826"}],"version-history":[{"count":23,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/15826\/revisions"}],"predecessor-version":[{"id":15871,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/15826\/revisions\/15871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/media\/15831"}],"wp:attachment":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/media?parent=15826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/categories?post=15826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/tags?post=15826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}