{"id":15760,"date":"2023-05-16T12:31:35","date_gmt":"2023-05-16T12:31:35","guid":{"rendered":"https:\/\/esi.uclm.es\/?p=15760"},"modified":"2023-05-17T11:05:29","modified_gmt":"2023-05-17T11:05:29","slug":"dorothy-monekosso-visita-el-grupo-air-y-la-esi","status":"publish","type":"post","link":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/16\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\/","title":{"rendered":"Dorothy Monekosso visita el grupo AIR y la ESI"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Dorothy Monekosso<\/strong>, Catedr\u00e1tica en Ingenier\u00eda Inform\u00e1tica en la <a href=\"https:\/\/www.durham.ac.uk\/\">Universidad de Durham<\/a>, y Directora T\u00e9cnica (CTO) de <a href=\"https:\/\/www.more-life.co.uk\/\">More Life UK Ltd<\/a>, es una investigadora destacada internacionalmente en el \u00e1mbito de las tecnolog\u00edas de asistencia m\u00e9dica y la rehabilitaci\u00f3n. Dorothy, a trav\u00e9s del <a href=\"http:\/\/dhat-research.org\/index.php\"><em>Digital Health Hub&nbsp;<\/em><\/a>, mantiene una estrecha colaboraci\u00f3n laboral con la spin-off <a href=\"https:\/\/www.furiouskoalas.com\/\">Furious Koalas<\/a> de la ESI y <a href=\"http:\/\/www.uclm.es\">UCLM<\/a>, as\u00ed como con el <a href=\"https:\/\/air.esi.uclm.es\/\">grupo de investigaci\u00f3n AIR<\/a> en la propia ESI. Durante el martes 16 de mayo Dorothy el grupo AIR mantuvieron una reuni\u00f3n de coordinaci\u00f3n relacionada con el proyecto de investigaci\u00f3n nacional \u00ab<em>Desarrollo, implementaci\u00f3n y despliegue en la nube de la plataforma REHAB-IMMERSIVE para la rehabilitaci\u00f3n de las extremidades superiores<\/em>\u00ab, coordinado con el <a href=\"https:\/\/hnparaplejicos.sanidad.castillalamancha.es\/\">Hospital Nacional de Parapl\u00e9jicos de Toledo<\/a> y financiado por el Ministerio de Ciencia e Innovaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/esi.uclm.es\/index.php\/2022\/12\/19\/rv-como-complemento-a-la-rehabilitacion-de-los-miembros-superiores\/\">[+] Conoce m\u00e1s sobre el proyecto Rehab-Immersive<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Breve BIO de Dorothy Monekosso<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Dorothy es Doctora (2000) en Ingenier\u00eda Aeroespacial, M\u00e1ster en Ingenier\u00eda de Sat\u00e9lites por el Centro Espacial de Surrey (Universidad de Surrey) y Licenciada en Ingenier\u00eda Electr\u00f3nica. Comenz\u00f3 su carrera en el sector espacial, desarrollando ordenadores de a bordo y sistemas de control para naves espaciales y sat\u00e9lites. Dorothy se interes\u00f3 por la Inteligencia Artificial durante su doctorado aplicando m\u00e9todos y t\u00e9cnicas de aprendizaje autom\u00e1tico a la autonom\u00eda de naves espaciales. Gracias a este trabajo, recibi\u00f3 el premio <a href=\"https:\/\/foresight.org\/\">Engineering Foresight<\/a> de la Real Academia de Ingenier\u00eda. Su investigaci\u00f3n actual aplica las mismas t\u00e9cnicas para desarrollar tecnolog\u00edas sanitarias innovadoras. En 2020 recibi\u00f3 una beca honor\u00edfica de la British Computer Society por su trabajo en tecnolog\u00edas de asistencia y rehabilitaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-gestor-del-servicio wp-block-embed-gestor-del-servicio wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"A framework to support the development of virtual reality applications in upper limb rehabilitation\" width=\"1060\" height=\"596\" src=\"https:\/\/www.youtube.com\/embed\/FhzBlR0wGIY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Dorothy Monekosso, Catedr\u00e1tica en Ingenier\u00eda Inform\u00e1tica en la Universidad de Durham, y Directora T\u00e9cnica (CTO) de More Life UK Ltd, es una investigadora destacada internacionalmente en el \u00e1mbito de las tecnolog\u00edas de asistencia m\u00e9dica y la rehabilitaci\u00f3n. Dorothy, a trav\u00e9s del Digital Health Hub&nbsp;, mantiene [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15762,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[619,620],"tags":[],"class_list":["post-15760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-investigacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dorothy Monekosso visita el grupo AIR y la ESI - Escuela Superior de Inform\u00e1tica de UCLM<\/title>\n<meta name=\"description\" content=\"Dorothy Monekosso, Catedr\u00e1tica en Ingenier\u00eda Inform\u00e1tica en la Universidad de Durham, y Directora T\u00e9cnica (CTO) de More Life UK Ltd, es una investigadora destacada internacionalmente en el \u00e1mbito de las tecnolog\u00edas de asistencia m\u00e9dica y la rehabilitaci\u00f3n. Dorothy, a trav\u00e9s del Digital Health Hub\u00a0, mantiene una estrecha colaboraci\u00f3n laboral con la spin-off Furious Koalas de la ESI y UCLM, as\u00ed como con el grupo de investigaci\u00f3n AIR en la propia ESI. Durante el martes 16 de mayo Dorothy el grupo AIR mantuvieron una reuni\u00f3n de coordinaci\u00f3n relacionada con el proyecto nacional &quot;Desarrollo, implementaci\u00f3n y despliegue en la nube de la plataforma REHAB-IMMERSIVE para la rehabilitaci\u00f3n de las extremidades superiores&quot;, coordinado con el Hospital Nacional de Parapl\u00e9jicos de Toledo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/esi.uclm.es\/index.php\/2023\/05\/16\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dorothy Monekosso visita el grupo AIR y la ESI - Escuela Superior de Inform\u00e1tica de UCLM\" \/>\n<meta property=\"og:description\" content=\"Dorothy Monekosso, Catedr\u00e1tica en Ingenier\u00eda Inform\u00e1tica en la Universidad de Durham, y Directora T\u00e9cnica (CTO) de More Life UK Ltd, es una investigadora destacada internacionalmente en el \u00e1mbito de las tecnolog\u00edas de asistencia m\u00e9dica y la rehabilitaci\u00f3n. Dorothy, a trav\u00e9s del Digital Health Hub\u00a0, mantiene una estrecha colaboraci\u00f3n laboral con la spin-off Furious Koalas de la ESI y UCLM, as\u00ed como con el grupo de investigaci\u00f3n AIR en la propia ESI. Durante el martes 16 de mayo Dorothy el grupo AIR mantuvieron una reuni\u00f3n de coordinaci\u00f3n relacionada con el proyecto nacional &quot;Desarrollo, implementaci\u00f3n y despliegue en la nube de la plataforma REHAB-IMMERSIVE para la rehabilitaci\u00f3n de las extremidades superiores&quot;, coordinado con el Hospital Nacional de Parapl\u00e9jicos de Toledo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esi.uclm.es\/index.php\/2023\/05\/16\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela Superior de Inform\u00e1tica de UCLM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-16T12:31:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-17T11:05:29+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/visita_dorothy.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"975\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"esiuclm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@esiuclm\" \/>\n<meta name=\"twitter:site\" content=\"@esiuclm\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"esiuclm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/16\\\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/16\\\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\\\/\"},\"author\":{\"name\":\"esiuclm\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/person\\\/d9a390095e8beeca5aced92acb17a530\"},\"headline\":\"Dorothy Monekosso visita el grupo AIR y la ESI\",\"datePublished\":\"2023-05-16T12:31:35+00:00\",\"dateModified\":\"2023-05-17T11:05:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/16\\\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\\\/\"},\"wordCount\":307,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/16\\\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/05\\\/visita_dorothy.webp\",\"articleSection\":[\"General\",\"Investigaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/16\\\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/16\\\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\\\/\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/16\\\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\\\/\",\"name\":\"Dorothy Monekosso visita el grupo AIR y la ESI - Escuela Superior de Inform\u00e1tica de UCLM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/16\\\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/16\\\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/05\\\/visita_dorothy.webp\",\"datePublished\":\"2023-05-16T12:31:35+00:00\",\"dateModified\":\"2023-05-17T11:05:29+00:00\",\"description\":\"Dorothy Monekosso, Catedr\u00e1tica en Ingenier\u00eda Inform\u00e1tica en la Universidad de Durham, y Directora T\u00e9cnica (CTO) de More Life UK Ltd, es una investigadora destacada internacionalmente en el \u00e1mbito de las tecnolog\u00edas de asistencia m\u00e9dica y la rehabilitaci\u00f3n. Dorothy, a trav\u00e9s del Digital Health Hub\u00a0, mantiene una estrecha colaboraci\u00f3n laboral con la spin-off Furious Koalas de la ESI y UCLM, as\u00ed como con el grupo de investigaci\u00f3n AIR en la propia ESI. Durante el martes 16 de mayo Dorothy el grupo AIR mantuvieron una reuni\u00f3n de coordinaci\u00f3n relacionada con el proyecto nacional \\\"Desarrollo, implementaci\u00f3n y despliegue en la nube de la plataforma REHAB-IMMERSIVE para la rehabilitaci\u00f3n de las extremidades superiores\\\", coordinado con el Hospital Nacional de Parapl\u00e9jicos de Toledo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/16\\\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/16\\\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/16\\\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/05\\\/visita_dorothy.webp\",\"contentUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/05\\\/visita_dorothy.webp\",\"width\":1300,\"height\":975,\"caption\":\"David Vallejo, Javier Albusac, Vanesa Herrera, Dorothy Monekosso y Santiago S\u00e1nchez\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/16\\\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/esi.uclm.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dorothy Monekosso visita el grupo AIR y la ESI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#website\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/\",\"name\":\"Escuela Superior de Inform\u00e1tica de UCLM en Ciudad Real, Castilla-La Mancha\",\"description\":\"La Escuela Superior de Inform\u00e1tica de Ciudad Real (Castilla-La Mancha), Universidad de Castilla-La Mancha es un centro universitario que imparte el ciclo completo de Ingenier\u00eda en Inform\u00e1tica: grado, m\u00e1ster y doctorado.\",\"publisher\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/esi.uclm.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\",\"name\":\"Escuela Superior de Inform\u00e1tica de UCLM\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2022\\\/03\\\/LogoESI_cabecera-1.png\",\"contentUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2022\\\/03\\\/LogoESI_cabecera-1.png\",\"width\":460,\"height\":184,\"caption\":\"Escuela Superior de Inform\u00e1tica de UCLM\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Escuela-Superior-de-Informtica-543261809027158\",\"https:\\\/\\\/x.com\\\/esiuclm\",\"https:\\\/\\\/www.instagram.com\\\/esiuclm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/esiuclm\",\"https:\\\/\\\/www.twitch.tv\\\/esiuclm\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/12656631\\\/admin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/person\\\/d9a390095e8beeca5aced92acb17a530\",\"name\":\"esiuclm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"caption\":\"esiuclm\"},\"sameAs\":[\"https:\\\/\\\/esi.uclm.es\"],\"url\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/author\\\/esiadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dorothy Monekosso visita el grupo AIR y la ESI - Escuela Superior de Inform\u00e1tica de UCLM","description":"Dorothy Monekosso, Catedr\u00e1tica en Ingenier\u00eda Inform\u00e1tica en la Universidad de Durham, y Directora T\u00e9cnica (CTO) de More Life UK Ltd, es una investigadora destacada internacionalmente en el \u00e1mbito de las tecnolog\u00edas de asistencia m\u00e9dica y la rehabilitaci\u00f3n. Dorothy, a trav\u00e9s del Digital Health Hub\u00a0, mantiene una estrecha colaboraci\u00f3n laboral con la spin-off Furious Koalas de la ESI y UCLM, as\u00ed como con el grupo de investigaci\u00f3n AIR en la propia ESI. Durante el martes 16 de mayo Dorothy el grupo AIR mantuvieron una reuni\u00f3n de coordinaci\u00f3n relacionada con el proyecto nacional \"Desarrollo, implementaci\u00f3n y despliegue en la nube de la plataforma REHAB-IMMERSIVE para la rehabilitaci\u00f3n de las extremidades superiores\", coordinado con el Hospital Nacional de Parapl\u00e9jicos de Toledo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/16\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\/","og_locale":"es_ES","og_type":"article","og_title":"Dorothy Monekosso visita el grupo AIR y la ESI - Escuela Superior de Inform\u00e1tica de UCLM","og_description":"Dorothy Monekosso, Catedr\u00e1tica en Ingenier\u00eda Inform\u00e1tica en la Universidad de Durham, y Directora T\u00e9cnica (CTO) de More Life UK Ltd, es una investigadora destacada internacionalmente en el \u00e1mbito de las tecnolog\u00edas de asistencia m\u00e9dica y la rehabilitaci\u00f3n. Dorothy, a trav\u00e9s del Digital Health Hub\u00a0, mantiene una estrecha colaboraci\u00f3n laboral con la spin-off Furious Koalas de la ESI y UCLM, as\u00ed como con el grupo de investigaci\u00f3n AIR en la propia ESI. Durante el martes 16 de mayo Dorothy el grupo AIR mantuvieron una reuni\u00f3n de coordinaci\u00f3n relacionada con el proyecto nacional \"Desarrollo, implementaci\u00f3n y despliegue en la nube de la plataforma REHAB-IMMERSIVE para la rehabilitaci\u00f3n de las extremidades superiores\", coordinado con el Hospital Nacional de Parapl\u00e9jicos de Toledo.","og_url":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/16\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\/","og_site_name":"Escuela Superior de Inform\u00e1tica de UCLM","article_publisher":"https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158","article_published_time":"2023-05-16T12:31:35+00:00","article_modified_time":"2023-05-17T11:05:29+00:00","og_image":[{"width":1300,"height":975,"url":"http:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/visita_dorothy.webp","type":"image\/webp"}],"author":"esiuclm","twitter_card":"summary_large_image","twitter_creator":"@esiuclm","twitter_site":"@esiuclm","twitter_misc":{"Escrito por":"esiuclm","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/16\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\/#article","isPartOf":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/16\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\/"},"author":{"name":"esiuclm","@id":"https:\/\/esi.uclm.es\/#\/schema\/person\/d9a390095e8beeca5aced92acb17a530"},"headline":"Dorothy Monekosso visita el grupo AIR y la ESI","datePublished":"2023-05-16T12:31:35+00:00","dateModified":"2023-05-17T11:05:29+00:00","mainEntityOfPage":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/16\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\/"},"wordCount":307,"commentCount":0,"publisher":{"@id":"https:\/\/esi.uclm.es\/#organization"},"image":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/16\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\/#primaryimage"},"thumbnailUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/visita_dorothy.webp","articleSection":["General","Investigaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/esi.uclm.es\/index.php\/2023\/05\/16\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/16\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\/","url":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/16\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\/","name":"Dorothy Monekosso visita el grupo AIR y la ESI - Escuela Superior de Inform\u00e1tica de UCLM","isPartOf":{"@id":"https:\/\/esi.uclm.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/16\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\/#primaryimage"},"image":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/16\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\/#primaryimage"},"thumbnailUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/visita_dorothy.webp","datePublished":"2023-05-16T12:31:35+00:00","dateModified":"2023-05-17T11:05:29+00:00","description":"Dorothy Monekosso, Catedr\u00e1tica en Ingenier\u00eda Inform\u00e1tica en la Universidad de Durham, y Directora T\u00e9cnica (CTO) de More Life UK Ltd, es una investigadora destacada internacionalmente en el \u00e1mbito de las tecnolog\u00edas de asistencia m\u00e9dica y la rehabilitaci\u00f3n. Dorothy, a trav\u00e9s del Digital Health Hub\u00a0, mantiene una estrecha colaboraci\u00f3n laboral con la spin-off Furious Koalas de la ESI y UCLM, as\u00ed como con el grupo de investigaci\u00f3n AIR en la propia ESI. Durante el martes 16 de mayo Dorothy el grupo AIR mantuvieron una reuni\u00f3n de coordinaci\u00f3n relacionada con el proyecto nacional \"Desarrollo, implementaci\u00f3n y despliegue en la nube de la plataforma REHAB-IMMERSIVE para la rehabilitaci\u00f3n de las extremidades superiores\", coordinado con el Hospital Nacional de Parapl\u00e9jicos de Toledo.","breadcrumb":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/16\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/esi.uclm.es\/index.php\/2023\/05\/16\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/16\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\/#primaryimage","url":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/visita_dorothy.webp","contentUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/visita_dorothy.webp","width":1300,"height":975,"caption":"David Vallejo, Javier Albusac, Vanesa Herrera, Dorothy Monekosso y Santiago S\u00e1nchez"},{"@type":"BreadcrumbList","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/16\/dorothy-monekosso-visita-el-grupo-air-y-la-esi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/esi.uclm.es\/"},{"@type":"ListItem","position":2,"name":"Dorothy Monekosso visita el grupo AIR y la ESI"}]},{"@type":"WebSite","@id":"https:\/\/esi.uclm.es\/#website","url":"https:\/\/esi.uclm.es\/","name":"Escuela Superior de Inform\u00e1tica de UCLM en Ciudad Real, Castilla-La Mancha","description":"La Escuela Superior de Inform\u00e1tica de Ciudad Real (Castilla-La Mancha), Universidad de Castilla-La Mancha es un centro universitario que imparte el ciclo completo de Ingenier\u00eda en Inform\u00e1tica: grado, m\u00e1ster y doctorado.","publisher":{"@id":"https:\/\/esi.uclm.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esi.uclm.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/esi.uclm.es\/#organization","name":"Escuela Superior de Inform\u00e1tica de UCLM","url":"https:\/\/esi.uclm.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esi.uclm.es\/#\/schema\/logo\/image\/","url":"https:\/\/esi.uclm.es\/assets\/uploads\/2022\/03\/LogoESI_cabecera-1.png","contentUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2022\/03\/LogoESI_cabecera-1.png","width":460,"height":184,"caption":"Escuela Superior de Inform\u00e1tica de UCLM"},"image":{"@id":"https:\/\/esi.uclm.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158","https:\/\/x.com\/esiuclm","https:\/\/www.instagram.com\/esiuclm\/","https:\/\/www.youtube.com\/user\/esiuclm","https:\/\/www.twitch.tv\/esiuclm","https:\/\/www.linkedin.com\/company\/12656631\/admin\/"]},{"@type":"Person","@id":"https:\/\/esi.uclm.es\/#\/schema\/person\/d9a390095e8beeca5aced92acb17a530","name":"esiuclm","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","caption":"esiuclm"},"sameAs":["https:\/\/esi.uclm.es"],"url":"https:\/\/esi.uclm.es\/index.php\/author\/esiadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/15760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/comments?post=15760"}],"version-history":[{"count":5,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/15760\/revisions"}],"predecessor-version":[{"id":15789,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/15760\/revisions\/15789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/media\/15762"}],"wp:attachment":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/media?parent=15760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/categories?post=15760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/tags?post=15760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}