{"id":15627,"date":"2023-05-07T08:36:32","date_gmt":"2023-05-07T08:36:32","guid":{"rendered":"https:\/\/esi.uclm.es\/?p=15627"},"modified":"2023-05-07T09:26:06","modified_gmt":"2023-05-07T09:26:06","slug":"biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez","status":"publish","type":"post","link":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/07\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\/","title":{"rendered":"Biblioteca ESI, mayo 2023: los 3+2 libros recomendados por Carlos Gonz\u00e1lez"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Carlos Gonz\u00e1lez Morcillo, Catedr\u00e1tico de la Escuela y Director Acad\u00e9mico de la UCLM protagoniza nuestra secci\u00f3n de biblioteca en el mes de mayo. Como ya sab\u00e9is, la secci\u00f3n 3+2 incluye la recomendaci\u00f3n de 3 libros relacionados con la tecnolog\u00eda y el \u00e1mbito profesional, y 2 libros de otras tem\u00e1ticas diversas. Estos son los libros que nos recomienda Carlos y por qu\u00e9:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Libros tecnol\u00f3gicos (3)<\/strong><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-vivid-cyan-blue-color has-alpha-channel-opacity has-vivid-cyan-blue-background-color has-background\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. Deep Work<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-663x1024.png\" alt=\"\" class=\"wp-image-15628\" width=\"332\" height=\"512\" srcset=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-663x1024.png 663w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-194x300.png 194w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-768x1187.png 768w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-994x1536.png 994w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-1326x2048.png 1326w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-1300x2009.png 1300w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-600x927.png 600w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image.png 1400w\" sizes=\"auto, (max-width: 332px) 100vw, 332px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abDeep Work\u00bb, escrito por el profesor de ciencias de la computaci\u00f3n Carl Newport, es un libro fascinante que explora la importancia de enfocarse profundamente en tareas cognitivamente demandantes para lograr un rendimiento m\u00e1ximo y aumentar la productividad. Newport argumenta que, en un mundo lleno de distracciones y tecnolog\u00eda omnipresente, nuestra capacidad para concentrarnos intensamente en tareas desafiantes es cada vez m\u00e1s valiosa y rara. A lo largo del libro, el autor ofrece estrategias y t\u00e9cnicas pr\u00e1cticas para desarrollar y mantener h\u00e1bitos de trabajo profundo, as\u00ed como ejemplos de personas exitosas que han adoptado estos principios en sus vidas profesionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Personalmente, me ha encantado \u00abDeep Work\u00bb porque aborda de manera efectiva uno de los mayores desaf\u00edos que enfrentamos hoy en d\u00eda: la lucha por mantener la concentraci\u00f3n en medio de un mundo repleto de distracciones digitales. Recomendar\u00eda \u00abDeep Work\u00bb a cualquier profesional de la inform\u00e1tica porque, en un campo donde el pensamiento creativo y la resoluci\u00f3n de problemas son fundamentales, la capacidad de sumergirse en el trabajo profundo es esencial para el \u00e9xito. Todos los que trabajamos en un entorno multi-pantalla, multi-pesta\u00f1a y multi-distracci\u00f3n deber\u00edamos estudiar y poner en pr\u00e1ctica las t\u00e9cnicas de este libro. A mi me ha ayudado mucho y por eso lo pongo como primera recomendaci\u00f3n.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. Human Compatible<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-1-678x1024.png\" alt=\"\" class=\"wp-image-15629\" width=\"339\" height=\"512\" srcset=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-1-678x1024.png 678w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-1-199x300.png 199w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-1-768x1160.png 768w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-1-1017x1536.png 1017w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-1-1356x2048.png 1356w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-1-1300x1963.png 1300w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-1-600x906.png 600w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-1.png 1695w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abHuman Compatible\u00bb de Stuart Russell es un libro delicioso que aborda la inteligencia artificial (IA) y sus implicaciones en el futuro de la humanidad. En este libro, Russell, un experto l\u00edder en el campo de la IA y autor del libro de cabecera sobre IA en estudios universitarios de inform\u00e1tica \u201cIA: Un enfoque moderno\u201d, ofrece una visi\u00f3n \u00fanica y cautivadora sobre c\u00f3mo garantizar que la IA sirva a nuestros intereses y evite consecuencias indeseadas. El autor plantea un enfoque completamente nuevo para el dise\u00f1o de sistemas de IA, denominado \u00abIA asistente\u00bb, en el que las m\u00e1quinas est\u00e1n dise\u00f1adas para entender y adaptarse a los objetivos humanos en lugar de seguir objetivos predefinidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este libro porque no solo ofrece una perspectiva bien fundamentada, accesible y visionaria sobre el futuro de la IA. La capacidad de Russell para explicar conceptos complejos de manera clara y su enfoque pragm\u00e1tico hacia el desarrollo de tecnolog\u00edas de IA que sean realmente compatibles con los seres humanos lo convierten en una lectura esencial e inspiradora para cualquiera interesado en el futuro de la inteligencia artificial y su impacto en nuestra sociedad. La siguiente era est\u00e1 muy muy muy cerca.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3. Deep Learning for Vision Systems<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-2-817x1024.png\" alt=\"\" class=\"wp-image-15632\" width=\"409\" height=\"512\" srcset=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-2-817x1024.png 817w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-2-239x300.png 239w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-2-768x962.png 768w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-2-600x752.png 600w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-2.png 1197w\" sizes=\"auto, (max-width: 409px) 100vw, 409px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abDeep Learning for Vision Systems\u00bb de Mohamed Elgendy es un libro completo que proporciona una s\u00f3lida introducci\u00f3n a la aplicaci\u00f3n de t\u00e9cnicas de aprendizaje profundo en sistemas de visi\u00f3n por computadora. Elgendy, un experto en inteligencia artificial y visi\u00f3n por computadora, presenta conceptos fundamentales, arquitecturas de redes neuronales convolucionales y diversas aplicaciones pr\u00e1cticas en este campo en r\u00e1pido crecimiento. El libro gu\u00eda a los lectores a trav\u00e9s de ejemplos pr\u00e1cticos y casos de estudio que demuestran c\u00f3mo implementar algoritmos de aprendizaje profundo para abordar problemas del mundo real en la visi\u00f3n por computadora, como la clasificaci\u00f3n de im\u00e1genes, la detecci\u00f3n de objetos y el reconocimiento facial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Me ha gustado especialmente este libro porque combina de manera efectiva la teor\u00eda y la pr\u00e1ctica, permitiendo adquirir una comprensi\u00f3n profunda de los conceptos fundamentales y las habilidades necesarias para aplicar el aprendizaje profundo en sistemas de visi\u00f3n. Elgendy hace un excelente trabajo al explicar conceptos complejos de manera clara y accesible, lo que facilita la comprensi\u00f3n de los principios del aprendizaje profundo para visiones incluso para aquellos que son nuevos en el campo. La gran cantidad de ejemplos pr\u00e1cticos y casos de estudio hacen de este libro una lectura valiosa y aplicable para cualquier persona interesada en desarrollar soluciones de visi\u00f3n por computadora basadas en aprendizaje profundo. \u00bfLo malo del libro? Como manual basado en tecnolog\u00edas espec\u00edficas, se quedar\u00e1 obsoleto muy pronto. Trab\u00e1jalo ya u olvida esta recomendaci\u00f3n.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:41px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Libros no tecnol\u00f3gicos (2)<\/strong><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-vivid-cyan-blue-color has-alpha-channel-opacity has-vivid-cyan-blue-background-color has-background\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4. Pre-suasi\u00f3n<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-3.png\" alt=\"\" class=\"wp-image-15633\" width=\"500\" height=\"500\" srcset=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-3.png 1000w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-3-300x300.png 300w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-3-150x150.png 150w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-3-768x768.png 768w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-3-550x550.png 550w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-3-600x600.png 600w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/image-3-100x100.png 100w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abPre-suasi\u00f3n: Un m\u00e9todo revolucionario para influir y persuadir\u00bb de Robert Cialdini es un libro revelador que explora el poder de la persuasi\u00f3n en el \u00e1mbito de la comunicaci\u00f3n y la toma de decisiones. Cialdini es el mayor experto mundial en psicolog\u00eda de la persuasi\u00f3n, autor de numerosos libros \u00e9xitos mundiales en esta tem\u00e1tica como \u201cInfluencia\u201d o \u201cS\u00ed!\u201d, en este libro introduce el concepto de \u00abpre-suasi\u00f3n\u00bb, que se refiere a la habilidad de preparar a las personas para que sean m\u00e1s receptivas a un mensaje antes de presentarlo. A trav\u00e9s de investigaciones y estudios de casos, el autor demuestra c\u00f3mo la pre-suasi\u00f3n puede ser utilizada de manera efectiva para influir en la percepci\u00f3n, las actitudes y las decisiones de los dem\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este libro me encanta porque ampl\u00eda nuestra comprensi\u00f3n de la persuasi\u00f3n y presenta una nueva perspectiva sobre c\u00f3mo persuadir a los dem\u00e1s de manera \u00e9tica y efectiva. La obra de Cialdini es fascinante y accesible, llena de ejemplos pr\u00e1cticos, met\u00e1foras e historias. Proporciona estrategias basadas en la investigaci\u00f3n que pueden aplicarse tanto en la vida personal como en el \u00e1mbito profesional. \u201cPre-suasi\u00f3n\u201d es una lectura esencial para cualquiera que se gane la vida hablando en p\u00fablico (\u00a1ojo profesores!) o cualquiera que tenga que vender una idea en p\u00fablico o en privado (\u00bfqui\u00e9n no?).<\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>5. Momentos m\u00e1gicos: C\u00f3mo crear experiencias que nos cambien la vida<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/81hSmRGEDeL-669x1024.webp\" alt=\"\" class=\"wp-image-15635\" width=\"335\" height=\"512\" srcset=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/81hSmRGEDeL-669x1024.webp 669w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/81hSmRGEDeL-196x300.webp 196w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/81hSmRGEDeL-768x1175.webp 768w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/81hSmRGEDeL-1004x1536.webp 1004w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/81hSmRGEDeL-1338x2048.webp 1338w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/81hSmRGEDeL-1300x1989.webp 1300w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/81hSmRGEDeL-600x918.webp 600w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/81hSmRGEDeL.webp 1673w\" sizes=\"auto, (max-width: 335px) 100vw, 335px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Podr\u00eda recomendar cualquier libro de los hermanos Chip y Dan Heath. Son mis autores favoritos en el \u00e1mbito de la productividad. Este libro en concreto es muy inspirador. Explora c\u00f3mo ciertos momentos pueden tener un impacto profundo y duradero en nuestras vidas. A trav\u00e9s de historias cautivadoras y estudios de casos, los autores demuestran c\u00f3mo estos momentos extraordinarios son el resultado de la combinaci\u00f3n de cuatro elementos clave: la elevaci\u00f3n, la conexi\u00f3n, la introspecci\u00f3n y la trascendencia. Adem\u00e1s, los hermanos Heath proporcionan herramientas y estrategias pr\u00e1cticas para crear y aprovechar estos momentos significativos tanto en nuestra vida personal como profesional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que me ha gustado especialmente de este libro es la forma en que los autores desglosan los elementos que conforman un momento poderoso y nos ense\u00f1an c\u00f3mo podemos aplicarlos y dise\u00f1arlos intencionalmente en nuestras propias vidas. La narrativa atractiva y las historias reales hacen que la lectura sea accesible y emocionante, al mismo tiempo que proporcionan lecciones valiosas sobre c\u00f3mo crear momentos memorables y transformadores. \u00abEl poder de los momentos\u00bb es una lectura enriquecedora para cualquiera que busque mejorar sus relaciones, su trabajo y su vida en general. Seguro que no te defraudar\u00e1. Y luego sigue con el resto de libros de los autores, todos igual de buenos. De nada.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Otras recomendaciones de libros de Biblioteca ESI<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-vivid-cyan-blue-color has-alpha-channel-opacity has-vivid-cyan-blue-background-color has-background\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/esi.uclm.es\/index.php\/2023\/04\/19\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\/\">[+] Abril 2023, 3+2 libros recomendados por Ana Mar\u00eda Fern\u00e1ndez<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/esi.uclm.es\/index.php\/2023\/03\/01\/biblioteca-esi-marzo-23-los-32-libros-recomendados-por-luis-cabanero\/\">[+] Marzo 2023, 3+2 libros recomendados por Luis Caba\u00f1ero<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a data-type=\"post\" data-id=\"14044\" href=\"https:\/\/esi.uclm.es\/index.php\/2023\/01\/31\/los-32-libros-recomendados-por-elena-desdentado\/\">[+] Febrero 2023, 3+2 libros recomendados por Elena Desdentado<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a data-type=\"post\" data-id=\"13780\" href=\"https:\/\/esi.uclm.es\/index.php\/2023\/01\/10\/los-5-libros-recomendados-por-raul-barba\/\">[+] Enero 2023, 3+2 libros recomendados por Ra\u00fal Barba<\/a><\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Comenta en redes<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-vivid-cyan-blue-color has-alpha-channel-opacity has-vivid-cyan-blue-background-color has-background\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<blockquote class=\"twitter-tweet\"><p lang=\"es\" dir=\"ltr\">\ud83d\udcda\ud83e\udde0 <a href=\"https:\/\/twitter.com\/cgmorcillo?ref_src=twsrc%5Etfw\">@cgmorcillo<\/a> protagonista de 3+2 libros recomendados en <a href=\"https:\/\/twitter.com\/hashtag\/ESIbiblioteca?src=hash&amp;ref_src=twsrc%5Etfw\">#ESIbiblioteca<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/mayo?src=hash&amp;ref_src=twsrc%5Etfw\">#mayo<\/a>: PRE-SUASION, Momentos M\u00e1gicos, Deep Work, Human Compatible y Deep Learning for Vision Systems.<br><br>Descubre por qu\u00e9 son interesantes sus lecturas \ud83d\udc49 <a href=\"https:\/\/t.co\/OaIwdtC7W7\">https:\/\/t.co\/OaIwdtC7W7<\/a><br><br>\ud83d\udd01\u2764\ufe0f (\ud83c\udf81 &#8211; 24h) <a href=\"https:\/\/t.co\/U0LOMrsFJE\">pic.twitter.com\/U0LOMrsFJE<\/a><\/p>&mdash; ES. Inform\u00e1tica UCLM (@esiuclm) <a href=\"https:\/\/twitter.com\/esiuclm\/status\/1655138732024950784?ref_src=twsrc%5Etfw\">May 7, 2023<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/Cr78FcONBAg\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/Cr78FcONBAg\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Ver esta publicaci\u00f3n en Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/Cr78FcONBAg\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener\">Una publicaci\u00f3n compartida por ESI (@esiuclm)<\/a><\/p><\/div><\/blockquote> <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQuieres conocer algunas de las lecturas favoritas de Carlos Gonz\u00e1lez? En nuestra secci\u00f3n de biblioteca de mayo, Carlos comparte sus 5 recomendaciones, desde libros que exploran el mundo de la tecnolog\u00eda y la inteligencia artificial, hasta obras que te ense\u00f1ar\u00e1n c\u00f3mo persuadir y crear momentos m\u00e1gicos en tu vida<\/p>\n","protected":false},"author":1,"featured_media":15637,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1815,619],"tags":[],"class_list":["post-15627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biblioteca","category-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biblioteca ESI, mayo 2023: los 3+2 libros recomendados por Carlos Gonz\u00e1lez - Escuela Superior de Inform\u00e1tica de UCLM<\/title>\n<meta name=\"description\" content=\"\u00bfQuieres saber cu\u00e1les son las lecturas favoritas de Carlos Gonz\u00e1lez Morcillo, Catedr\u00e1tico de la Escuela y Director Acad\u00e9mico de la UCLM? En nuestra secci\u00f3n de biblioteca de mayo, Carlos comparte sus 5 recomendaciones, desde libros que exploran el mundo de la tecnolog\u00eda y la inteligencia artificial, hasta obras que te ense\u00f1ar\u00e1n c\u00f3mo persuadir y crear momentos m\u00e1gicos en tu vida\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/esi.uclm.es\/index.php\/2023\/05\/07\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biblioteca ESI, mayo 2023: los 3+2 libros recomendados por Carlos Gonz\u00e1lez - Escuela Superior de Inform\u00e1tica de UCLM\" \/>\n<meta property=\"og:description\" content=\"\u00bfQuieres saber cu\u00e1les son las lecturas favoritas de Carlos Gonz\u00e1lez Morcillo, Catedr\u00e1tico de la Escuela y Director Acad\u00e9mico de la UCLM? En nuestra secci\u00f3n de biblioteca de mayo, Carlos comparte sus 5 recomendaciones, desde libros que exploran el mundo de la tecnolog\u00eda y la inteligencia artificial, hasta obras que te ense\u00f1ar\u00e1n c\u00f3mo persuadir y crear momentos m\u00e1gicos en tu vida\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esi.uclm.es\/index.php\/2023\/05\/07\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela Superior de Inform\u00e1tica de UCLM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-07T08:36:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-07T09:26:06+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/carlos_libros_web.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"865\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"esiuclm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@esiuclm\" \/>\n<meta name=\"twitter:site\" content=\"@esiuclm\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"esiuclm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/07\\\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/07\\\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\\\/\"},\"author\":{\"name\":\"esiuclm\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/person\\\/d9a390095e8beeca5aced92acb17a530\"},\"headline\":\"Biblioteca ESI, mayo 2023: los 3+2 libros recomendados por Carlos Gonz\u00e1lez\",\"datePublished\":\"2023-05-07T08:36:32+00:00\",\"dateModified\":\"2023-05-07T09:26:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/07\\\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\\\/\"},\"wordCount\":1363,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/07\\\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/05\\\/carlos_libros_web.webp\",\"articleSection\":[\"Biblioteca\",\"General\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/07\\\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/07\\\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\\\/\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/07\\\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\\\/\",\"name\":\"Biblioteca ESI, mayo 2023: los 3+2 libros recomendados por Carlos Gonz\u00e1lez - Escuela Superior de Inform\u00e1tica de UCLM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/07\\\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/07\\\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/05\\\/carlos_libros_web.webp\",\"datePublished\":\"2023-05-07T08:36:32+00:00\",\"dateModified\":\"2023-05-07T09:26:06+00:00\",\"description\":\"\u00bfQuieres saber cu\u00e1les son las lecturas favoritas de Carlos Gonz\u00e1lez Morcillo, Catedr\u00e1tico de la Escuela y Director Acad\u00e9mico de la UCLM? En nuestra secci\u00f3n de biblioteca de mayo, Carlos comparte sus 5 recomendaciones, desde libros que exploran el mundo de la tecnolog\u00eda y la inteligencia artificial, hasta obras que te ense\u00f1ar\u00e1n c\u00f3mo persuadir y crear momentos m\u00e1gicos en tu vida\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/07\\\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/07\\\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/07\\\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/05\\\/carlos_libros_web.webp\",\"contentUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/05\\\/carlos_libros_web.webp\",\"width\":1400,\"height\":865,\"caption\":\"Carlos Gonz\u00e1lez Morcillo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/05\\\/07\\\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/esi.uclm.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biblioteca ESI, mayo 2023: los 3+2 libros recomendados por Carlos Gonz\u00e1lez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#website\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/\",\"name\":\"Escuela Superior de Inform\u00e1tica de UCLM en Ciudad Real, Castilla-La Mancha\",\"description\":\"La Escuela Superior de Inform\u00e1tica de Ciudad Real (Castilla-La Mancha), Universidad de Castilla-La Mancha es un centro universitario que imparte el ciclo completo de Ingenier\u00eda en Inform\u00e1tica: grado, m\u00e1ster y doctorado.\",\"publisher\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/esi.uclm.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\",\"name\":\"Escuela Superior de Inform\u00e1tica de UCLM\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2022\\\/03\\\/LogoESI_cabecera-1.png\",\"contentUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2022\\\/03\\\/LogoESI_cabecera-1.png\",\"width\":460,\"height\":184,\"caption\":\"Escuela Superior de Inform\u00e1tica de UCLM\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Escuela-Superior-de-Informtica-543261809027158\",\"https:\\\/\\\/x.com\\\/esiuclm\",\"https:\\\/\\\/www.instagram.com\\\/esiuclm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/esiuclm\",\"https:\\\/\\\/www.twitch.tv\\\/esiuclm\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/12656631\\\/admin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/person\\\/d9a390095e8beeca5aced92acb17a530\",\"name\":\"esiuclm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"caption\":\"esiuclm\"},\"sameAs\":[\"https:\\\/\\\/esi.uclm.es\"],\"url\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/author\\\/esiadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biblioteca ESI, mayo 2023: los 3+2 libros recomendados por Carlos Gonz\u00e1lez - Escuela Superior de Inform\u00e1tica de UCLM","description":"\u00bfQuieres saber cu\u00e1les son las lecturas favoritas de Carlos Gonz\u00e1lez Morcillo, Catedr\u00e1tico de la Escuela y Director Acad\u00e9mico de la UCLM? En nuestra secci\u00f3n de biblioteca de mayo, Carlos comparte sus 5 recomendaciones, desde libros que exploran el mundo de la tecnolog\u00eda y la inteligencia artificial, hasta obras que te ense\u00f1ar\u00e1n c\u00f3mo persuadir y crear momentos m\u00e1gicos en tu vida","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/07\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\/","og_locale":"es_ES","og_type":"article","og_title":"Biblioteca ESI, mayo 2023: los 3+2 libros recomendados por Carlos Gonz\u00e1lez - Escuela Superior de Inform\u00e1tica de UCLM","og_description":"\u00bfQuieres saber cu\u00e1les son las lecturas favoritas de Carlos Gonz\u00e1lez Morcillo, Catedr\u00e1tico de la Escuela y Director Acad\u00e9mico de la UCLM? En nuestra secci\u00f3n de biblioteca de mayo, Carlos comparte sus 5 recomendaciones, desde libros que exploran el mundo de la tecnolog\u00eda y la inteligencia artificial, hasta obras que te ense\u00f1ar\u00e1n c\u00f3mo persuadir y crear momentos m\u00e1gicos en tu vida","og_url":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/07\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\/","og_site_name":"Escuela Superior de Inform\u00e1tica de UCLM","article_publisher":"https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158","article_published_time":"2023-05-07T08:36:32+00:00","article_modified_time":"2023-05-07T09:26:06+00:00","og_image":[{"width":1400,"height":865,"url":"http:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/carlos_libros_web.webp","type":"image\/webp"}],"author":"esiuclm","twitter_card":"summary_large_image","twitter_creator":"@esiuclm","twitter_site":"@esiuclm","twitter_misc":{"Escrito por":"esiuclm","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/07\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\/#article","isPartOf":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/07\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\/"},"author":{"name":"esiuclm","@id":"https:\/\/esi.uclm.es\/#\/schema\/person\/d9a390095e8beeca5aced92acb17a530"},"headline":"Biblioteca ESI, mayo 2023: los 3+2 libros recomendados por Carlos Gonz\u00e1lez","datePublished":"2023-05-07T08:36:32+00:00","dateModified":"2023-05-07T09:26:06+00:00","mainEntityOfPage":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/07\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\/"},"wordCount":1363,"commentCount":0,"publisher":{"@id":"https:\/\/esi.uclm.es\/#organization"},"image":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/07\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\/#primaryimage"},"thumbnailUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/carlos_libros_web.webp","articleSection":["Biblioteca","General"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/esi.uclm.es\/index.php\/2023\/05\/07\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/07\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\/","url":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/07\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\/","name":"Biblioteca ESI, mayo 2023: los 3+2 libros recomendados por Carlos Gonz\u00e1lez - Escuela Superior de Inform\u00e1tica de UCLM","isPartOf":{"@id":"https:\/\/esi.uclm.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/07\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\/#primaryimage"},"image":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/07\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\/#primaryimage"},"thumbnailUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/carlos_libros_web.webp","datePublished":"2023-05-07T08:36:32+00:00","dateModified":"2023-05-07T09:26:06+00:00","description":"\u00bfQuieres saber cu\u00e1les son las lecturas favoritas de Carlos Gonz\u00e1lez Morcillo, Catedr\u00e1tico de la Escuela y Director Acad\u00e9mico de la UCLM? En nuestra secci\u00f3n de biblioteca de mayo, Carlos comparte sus 5 recomendaciones, desde libros que exploran el mundo de la tecnolog\u00eda y la inteligencia artificial, hasta obras que te ense\u00f1ar\u00e1n c\u00f3mo persuadir y crear momentos m\u00e1gicos en tu vida","breadcrumb":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/07\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/esi.uclm.es\/index.php\/2023\/05\/07\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/07\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\/#primaryimage","url":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/carlos_libros_web.webp","contentUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/05\/carlos_libros_web.webp","width":1400,"height":865,"caption":"Carlos Gonz\u00e1lez Morcillo"},{"@type":"BreadcrumbList","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/05\/07\/biblioteca-esi-mayo-2023-los-32-libros-recomendados-por-carlos-gonzalez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/esi.uclm.es\/"},{"@type":"ListItem","position":2,"name":"Biblioteca ESI, mayo 2023: los 3+2 libros recomendados por Carlos Gonz\u00e1lez"}]},{"@type":"WebSite","@id":"https:\/\/esi.uclm.es\/#website","url":"https:\/\/esi.uclm.es\/","name":"Escuela Superior de Inform\u00e1tica de UCLM en Ciudad Real, Castilla-La Mancha","description":"La Escuela Superior de Inform\u00e1tica de Ciudad Real (Castilla-La Mancha), Universidad de Castilla-La Mancha es un centro universitario que imparte el ciclo completo de Ingenier\u00eda en Inform\u00e1tica: grado, m\u00e1ster y doctorado.","publisher":{"@id":"https:\/\/esi.uclm.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esi.uclm.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/esi.uclm.es\/#organization","name":"Escuela Superior de Inform\u00e1tica de UCLM","url":"https:\/\/esi.uclm.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esi.uclm.es\/#\/schema\/logo\/image\/","url":"https:\/\/esi.uclm.es\/assets\/uploads\/2022\/03\/LogoESI_cabecera-1.png","contentUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2022\/03\/LogoESI_cabecera-1.png","width":460,"height":184,"caption":"Escuela Superior de Inform\u00e1tica de UCLM"},"image":{"@id":"https:\/\/esi.uclm.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158","https:\/\/x.com\/esiuclm","https:\/\/www.instagram.com\/esiuclm\/","https:\/\/www.youtube.com\/user\/esiuclm","https:\/\/www.twitch.tv\/esiuclm","https:\/\/www.linkedin.com\/company\/12656631\/admin\/"]},{"@type":"Person","@id":"https:\/\/esi.uclm.es\/#\/schema\/person\/d9a390095e8beeca5aced92acb17a530","name":"esiuclm","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","caption":"esiuclm"},"sameAs":["https:\/\/esi.uclm.es"],"url":"https:\/\/esi.uclm.es\/index.php\/author\/esiadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/15627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/comments?post=15627"}],"version-history":[{"count":6,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/15627\/revisions"}],"predecessor-version":[{"id":15641,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/15627\/revisions\/15641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/media\/15637"}],"wp:attachment":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/media?parent=15627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/categories?post=15627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/tags?post=15627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}