{"id":15338,"date":"2023-04-19T08:35:47","date_gmt":"2023-04-19T08:35:47","guid":{"rendered":"https:\/\/esi.uclm.es\/?p=15338"},"modified":"2023-04-19T08:48:12","modified_gmt":"2023-04-19T08:48:12","slug":"biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez","status":"publish","type":"post","link":"https:\/\/esi.uclm.es\/index.php\/2023\/04\/19\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\/","title":{"rendered":"Biblioteca ESI, abril 23: los 3+2 libros recomendados por Ana M. Fern\u00e1ndez"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nos adelantamos al d\u00eda del libro que se celebrar\u00e1 el Domingo 23 de abril. La secci\u00f3n de 3+2 libros del mes de abril est\u00e1 protagonizada por Ana Mar\u00eda Fern\u00e1ndez Saez, Doctora en Ingenier\u00eda Inform\u00e1tica, Profesora Asociada en la Escuela Superior de Inform\u00e1tica (<a href=\"http:\/\/www.uclm.es\">UCLM<\/a>), e investigadora en el <a href=\"https:\/\/alarcos.esi.uclm.es\/\">grupo ALARCOS<\/a>. Como es habitual, la protagonista de esta secci\u00f3n propone cinco libros, de los cuales tres de ellos est\u00e1n directamente relacionados con la Inform\u00e1tica, y otros dos que no lo est\u00e1n. Estos son los libros que os recomienda Ana y por qu\u00e9:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Libros tecnol\u00f3gicos (3)<\/strong><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-vivid-cyan-blue-color has-alpha-channel-opacity has-vivid-cyan-blue-background-color has-background\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">1. <strong>Data: A Guide to Humans (Phil Harvey, Noelia Jim\u00e9nez Mart\u00ednez). <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es un libro muy interesante que nos ense\u00f1a porqu\u00e9 los datos son tan importantes en el mundo actual. Muestra c\u00f3mo las empresas (y los gobiernos) hacen Big Data con toda la informaci\u00f3n que hay disponible sobre nosotros en internet y la utilizan para sus propios fines. \u00bfOs suena eso de que Instagram os muestre publicidad de algo que parece SUPER adecuado para ti? Pues no es casualidad. Adem\u00e1s, este libro indaga un poco en una \u201cutop\u00eda\u201d en la que el uso de los datos no se olvida de las necesidades\/sentimientos de las personas de las que proceden esos datos para poder extraer el m\u00e1ximo beneficio de los mismos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/image-4.png\" alt=\"\" class=\"wp-image-15350\" width=\"162\" height=\"250\" srcset=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/image-4.png 324w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/image-4-195x300.png 195w\" sizes=\"auto, (max-width: 162px) 100vw, 162px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">2. <strong>Patrones de dise\u00f1o aplicados a JAVA (Stephen Stelting, Olav Maasen), Ed. Prentice Hall. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es un libro muy pr\u00e1ctico, que nos aclara con muchos ejemplos f\u00e1ciles de entender los famosos patrones de dise\u00f1o. Cuando yo estudiaba, los patrones de dise\u00f1o eran unos grandes desconocidos hasta el \u00faltimo curso. Aprender a utilizarlos antes puede ayudar a evitar \u201cmalos vicios\u201d que luego cuesta mucho quitarse. En mi caso, durante los estudios aprend\u00ed la teor\u00eda de los patrones para poder aprobar, pero cuando me incorpor\u00e9 al mundo laboral me toc\u00f3 entenderlos muy bien para poder ponerlos correctamente en pr\u00e1ctica. Este libro fue una gran ayuda para m\u00ed.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/image.png\" alt=\"\" class=\"wp-image-15345\" width=\"192\" height=\"250\" srcset=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/image.png 766w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/image-230x300.png 230w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/image-600x783.png 600w\" sizes=\"auto, (max-width: 192px) 100vw, 192px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">3. <strong><strong>Optimizaci\u00f3n SQL en Oracle (Javier Morales Carreras).<\/strong> <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es un libro que me parece s\u00faper interesante y necesario para cualquier programador que trabaje con bases de datos en Oracle.&nbsp; En este tipo de puestos de trabajo pueden surgir problemas relacionados con la optimizaci\u00f3n de sentencias SQL y recursos de una base de datos, y este libro es una gran ayuda ya que trata aspectos muy espec\u00edficos que solo suelen verse en cursos especializados (y que suelen ser caros). Es un libro pr\u00e1ctico casi al 100% y muy f\u00e1cil de seguir.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/image-1-712x1024.png\" alt=\"\" class=\"wp-image-15346\" width=\"178\" height=\"256\" srcset=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/image-1-712x1024.png 712w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/image-1-209x300.png 209w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/image-1-768x1104.png 768w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/image-1-600x863.png 600w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/image-1.png 946w\" sizes=\"auto, (max-width: 178px) 100vw, 178px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Libros no tecnol\u00f3gicos (2)<\/strong><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-vivid-cyan-blue-color has-alpha-channel-opacity has-vivid-cyan-blue-background-color has-background\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">1. <strong>F\u00edsica y Berenjenas: La belleza invisible del Universo (Andr\u00e9s Gomberoff), Ed. Debate.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En peque\u00f1os cap\u00edtulos, explica de forma sencilla y amena distintos apartados de la f\u00edsica: calor, estructura del \u00e1tomo, aparici\u00f3n de los distintos elementos, colores, dualidad onda-part\u00edcula, agujeros negros, importancia de la investigaci\u00f3n b\u00e1sica, etc.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/image-2.png\" alt=\"\" class=\"wp-image-15347\" width=\"169\" height=\"250\" srcset=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/image-2.png 338w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/image-2-203x300.png 203w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">2. <strong>Breves respuestas a las grandes preguntas (Stephen Hawking), Ed. Critica.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Intenta dar respuestas de forma sencilla a esas preguntas tan complejas que nos pueden rondar la cabeza a todos alguna vez. Le pone mucho humor y adem\u00e1s explica de la forma m\u00e1s amena y sencilla posible unas preguntas cuya base f\u00edsica se escapa mucho de ser f\u00e1cilmente entendible.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/image-3.png\" alt=\"\" class=\"wp-image-15348\" width=\"172\" height=\"277\" srcset=\"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/image-3.png 229w, https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/image-3-186x300.png 186w\" sizes=\"auto, (max-width: 172px) 100vw, 172px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Otras recomendaciones de libros de Biblioteca ESI<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-vivid-cyan-blue-color has-alpha-channel-opacity has-vivid-cyan-blue-background-color has-background\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/esi.uclm.es\/index.php\/2023\/03\/01\/biblioteca-esi-marzo-23-los-32-libros-recomendados-por-luis-cabanero\/\">[+] Marzo 2023, 3+2 libros recomendados por Luis Caba\u00f1ero<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a data-type=\"post\" data-id=\"14044\" href=\"https:\/\/esi.uclm.es\/index.php\/2023\/01\/31\/los-32-libros-recomendados-por-elena-desdentado\/\">[+] Febrero 2023, 3+2 libros recomendados por Elena Desdentado<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a data-type=\"post\" data-id=\"13780\" href=\"https:\/\/esi.uclm.es\/index.php\/2023\/01\/10\/los-5-libros-recomendados-por-raul-barba\/\">[+] Enero 2023, 3+2 libros recomendados por Ra\u00fal Barba<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Comenta en redes<\/h2>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-vivid-cyan-blue-color has-alpha-channel-opacity has-vivid-cyan-blue-background-color has-background\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<blockquote class=\"twitter-tweet\"><p lang=\"es\" dir=\"ltr\">\ud83d\udcda Nos adelantamos al <a href=\"https:\/\/twitter.com\/hashtag\/DiadelLibro2023?src=hash&amp;ref_src=twsrc%5Etfw\">#DiadelLibro2023<\/a>. Nuestra secci\u00f3n de 3+2 libros recomendados del mes de abril est\u00e1 protagonizada por Ana M. Fdez Saez, Dr. en Ing. <a href=\"https:\/\/twitter.com\/hashtag\/Inform%C3%A1tica?src=hash&amp;ref_src=twsrc%5Etfw\">#Inform\u00e1tica<\/a>, Profesora Asociada e investigadora en <a href=\"https:\/\/twitter.com\/GrupoAlarcos?ref_src=twsrc%5Etfw\">@GrupoAlarcos<\/a> <br><br>\ud83d\udc49 \u00bfQuieres saber que libros son? <a href=\"https:\/\/t.co\/jC8ZdJNe2Q\">https:\/\/t.co\/jC8ZdJNe2Q<\/a> <a href=\"https:\/\/t.co\/VIG0wwIfA7\">pic.twitter.com\/VIG0wwIfA7<\/a><\/p>&mdash; ES. Inform\u00e1tica UCLM (@esiuclm) <a href=\"https:\/\/twitter.com\/esiuclm\/status\/1648608800729968640?ref_src=twsrc%5Etfw\">April 19, 2023<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CrNieaDtiSG\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CrNieaDtiSG\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Ver esta publicaci\u00f3n en Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CrNieaDtiSG\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener\">Una publicaci\u00f3n compartida por ESI (@esiuclm)<\/a><\/p><\/div><\/blockquote> <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nos adelantamos al d\u00eda del libro que se celebrar\u00e1 el Domingo 23 de abril. La secci\u00f3n de 3+2 libros del mes de abril est\u00e1 protagonizada por Ana Mar\u00eda Fern\u00e1ndez Saez, Doctora en Ingenier\u00eda Inform\u00e1tica, Profesora Asociada en la Escuela Superior de Inform\u00e1tica (UCLM), e investigadora [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15339,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1815,619],"tags":[],"class_list":["post-15338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biblioteca","category-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biblioteca ESI, abril 23: los 3+2 libros recomendados por Ana M. Fern\u00e1ndez - Escuela Superior de Inform\u00e1tica de UCLM<\/title>\n<meta name=\"description\" content=\"En esta secci\u00f3n recomendamos 5 interesantes libros, 3 relacionados con la inform\u00e1tica y 2 relacionados con cualquier otro \u00e1mbito. \u00bfQuieres saber los libros que recomienda Ana?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/esi.uclm.es\/index.php\/2023\/04\/19\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biblioteca ESI, abril 23: los 3+2 libros recomendados por Ana M. Fern\u00e1ndez - Escuela Superior de Inform\u00e1tica de UCLM\" \/>\n<meta property=\"og:description\" content=\"En esta secci\u00f3n recomendamos 5 interesantes libros, 3 relacionados con la inform\u00e1tica y 2 relacionados con cualquier otro \u00e1mbito. \u00bfQuieres saber los libros que recomienda Ana?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esi.uclm.es\/index.php\/2023\/04\/19\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\/\" \/>\n<meta property=\"og:site_name\" content=\"Escuela Superior de Inform\u00e1tica de UCLM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-19T08:35:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-19T08:48:12+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/ana_libros_web.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"865\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"esiuclm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@esiuclm\" \/>\n<meta name=\"twitter:site\" content=\"@esiuclm\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"esiuclm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/04\\\/19\\\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/04\\\/19\\\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\\\/\"},\"author\":{\"name\":\"esiuclm\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/person\\\/d9a390095e8beeca5aced92acb17a530\"},\"headline\":\"Biblioteca ESI, abril 23: los 3+2 libros recomendados por Ana M. Fern\u00e1ndez\",\"datePublished\":\"2023-04-19T08:35:47+00:00\",\"dateModified\":\"2023-04-19T08:48:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/04\\\/19\\\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\\\/\"},\"wordCount\":664,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/04\\\/19\\\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/04\\\/ana_libros_web.webp\",\"articleSection\":[\"Biblioteca\",\"General\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/04\\\/19\\\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/04\\\/19\\\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\\\/\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/04\\\/19\\\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\\\/\",\"name\":\"Biblioteca ESI, abril 23: los 3+2 libros recomendados por Ana M. Fern\u00e1ndez - Escuela Superior de Inform\u00e1tica de UCLM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/04\\\/19\\\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/04\\\/19\\\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/04\\\/ana_libros_web.webp\",\"datePublished\":\"2023-04-19T08:35:47+00:00\",\"dateModified\":\"2023-04-19T08:48:12+00:00\",\"description\":\"En esta secci\u00f3n recomendamos 5 interesantes libros, 3 relacionados con la inform\u00e1tica y 2 relacionados con cualquier otro \u00e1mbito. \u00bfQuieres saber los libros que recomienda Ana?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/04\\\/19\\\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/04\\\/19\\\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/04\\\/19\\\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/04\\\/ana_libros_web.webp\",\"contentUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2023\\\/04\\\/ana_libros_web.webp\",\"width\":1400,\"height\":865,\"caption\":\"Ana Mar\u00eda Fern\u00e1ndez Saez\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/2023\\\/04\\\/19\\\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/esi.uclm.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biblioteca ESI, abril 23: los 3+2 libros recomendados por Ana M. Fern\u00e1ndez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#website\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/\",\"name\":\"Escuela Superior de Inform\u00e1tica de UCLM en Ciudad Real, Castilla-La Mancha\",\"description\":\"La Escuela Superior de Inform\u00e1tica de Ciudad Real (Castilla-La Mancha), Universidad de Castilla-La Mancha es un centro universitario que imparte el ciclo completo de Ingenier\u00eda en Inform\u00e1tica: grado, m\u00e1ster y doctorado.\",\"publisher\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/esi.uclm.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#organization\",\"name\":\"Escuela Superior de Inform\u00e1tica de UCLM\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2022\\\/03\\\/LogoESI_cabecera-1.png\",\"contentUrl\":\"https:\\\/\\\/esi.uclm.es\\\/assets\\\/uploads\\\/2022\\\/03\\\/LogoESI_cabecera-1.png\",\"width\":460,\"height\":184,\"caption\":\"Escuela Superior de Inform\u00e1tica de UCLM\"},\"image\":{\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Escuela-Superior-de-Informtica-543261809027158\",\"https:\\\/\\\/x.com\\\/esiuclm\",\"https:\\\/\\\/www.instagram.com\\\/esiuclm\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/esiuclm\",\"https:\\\/\\\/www.twitch.tv\\\/esiuclm\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/12656631\\\/admin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/esi.uclm.es\\\/#\\\/schema\\\/person\\\/d9a390095e8beeca5aced92acb17a530\",\"name\":\"esiuclm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g\",\"caption\":\"esiuclm\"},\"sameAs\":[\"https:\\\/\\\/esi.uclm.es\"],\"url\":\"https:\\\/\\\/esi.uclm.es\\\/index.php\\\/author\\\/esiadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biblioteca ESI, abril 23: los 3+2 libros recomendados por Ana M. Fern\u00e1ndez - Escuela Superior de Inform\u00e1tica de UCLM","description":"En esta secci\u00f3n recomendamos 5 interesantes libros, 3 relacionados con la inform\u00e1tica y 2 relacionados con cualquier otro \u00e1mbito. \u00bfQuieres saber los libros que recomienda Ana?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/esi.uclm.es\/index.php\/2023\/04\/19\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\/","og_locale":"es_ES","og_type":"article","og_title":"Biblioteca ESI, abril 23: los 3+2 libros recomendados por Ana M. Fern\u00e1ndez - Escuela Superior de Inform\u00e1tica de UCLM","og_description":"En esta secci\u00f3n recomendamos 5 interesantes libros, 3 relacionados con la inform\u00e1tica y 2 relacionados con cualquier otro \u00e1mbito. \u00bfQuieres saber los libros que recomienda Ana?","og_url":"https:\/\/esi.uclm.es\/index.php\/2023\/04\/19\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\/","og_site_name":"Escuela Superior de Inform\u00e1tica de UCLM","article_publisher":"https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158","article_published_time":"2023-04-19T08:35:47+00:00","article_modified_time":"2023-04-19T08:48:12+00:00","og_image":[{"width":1400,"height":865,"url":"http:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/ana_libros_web.webp","type":"image\/webp"}],"author":"esiuclm","twitter_card":"summary_large_image","twitter_creator":"@esiuclm","twitter_site":"@esiuclm","twitter_misc":{"Escrito por":"esiuclm","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/04\/19\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\/#article","isPartOf":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/04\/19\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\/"},"author":{"name":"esiuclm","@id":"https:\/\/esi.uclm.es\/#\/schema\/person\/d9a390095e8beeca5aced92acb17a530"},"headline":"Biblioteca ESI, abril 23: los 3+2 libros recomendados por Ana M. Fern\u00e1ndez","datePublished":"2023-04-19T08:35:47+00:00","dateModified":"2023-04-19T08:48:12+00:00","mainEntityOfPage":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/04\/19\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\/"},"wordCount":664,"commentCount":0,"publisher":{"@id":"https:\/\/esi.uclm.es\/#organization"},"image":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/04\/19\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\/#primaryimage"},"thumbnailUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/ana_libros_web.webp","articleSection":["Biblioteca","General"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/esi.uclm.es\/index.php\/2023\/04\/19\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/04\/19\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\/","url":"https:\/\/esi.uclm.es\/index.php\/2023\/04\/19\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\/","name":"Biblioteca ESI, abril 23: los 3+2 libros recomendados por Ana M. Fern\u00e1ndez - Escuela Superior de Inform\u00e1tica de UCLM","isPartOf":{"@id":"https:\/\/esi.uclm.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/04\/19\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\/#primaryimage"},"image":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/04\/19\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\/#primaryimage"},"thumbnailUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/ana_libros_web.webp","datePublished":"2023-04-19T08:35:47+00:00","dateModified":"2023-04-19T08:48:12+00:00","description":"En esta secci\u00f3n recomendamos 5 interesantes libros, 3 relacionados con la inform\u00e1tica y 2 relacionados con cualquier otro \u00e1mbito. \u00bfQuieres saber los libros que recomienda Ana?","breadcrumb":{"@id":"https:\/\/esi.uclm.es\/index.php\/2023\/04\/19\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/esi.uclm.es\/index.php\/2023\/04\/19\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/04\/19\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\/#primaryimage","url":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/ana_libros_web.webp","contentUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2023\/04\/ana_libros_web.webp","width":1400,"height":865,"caption":"Ana Mar\u00eda Fern\u00e1ndez Saez"},{"@type":"BreadcrumbList","@id":"https:\/\/esi.uclm.es\/index.php\/2023\/04\/19\/biblioteca-esi-abril-23-los-32-libros-recomendados-por-ana-m-fernandez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/esi.uclm.es\/"},{"@type":"ListItem","position":2,"name":"Biblioteca ESI, abril 23: los 3+2 libros recomendados por Ana M. Fern\u00e1ndez"}]},{"@type":"WebSite","@id":"https:\/\/esi.uclm.es\/#website","url":"https:\/\/esi.uclm.es\/","name":"Escuela Superior de Inform\u00e1tica de UCLM en Ciudad Real, Castilla-La Mancha","description":"La Escuela Superior de Inform\u00e1tica de Ciudad Real (Castilla-La Mancha), Universidad de Castilla-La Mancha es un centro universitario que imparte el ciclo completo de Ingenier\u00eda en Inform\u00e1tica: grado, m\u00e1ster y doctorado.","publisher":{"@id":"https:\/\/esi.uclm.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esi.uclm.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/esi.uclm.es\/#organization","name":"Escuela Superior de Inform\u00e1tica de UCLM","url":"https:\/\/esi.uclm.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/esi.uclm.es\/#\/schema\/logo\/image\/","url":"https:\/\/esi.uclm.es\/assets\/uploads\/2022\/03\/LogoESI_cabecera-1.png","contentUrl":"https:\/\/esi.uclm.es\/assets\/uploads\/2022\/03\/LogoESI_cabecera-1.png","width":460,"height":184,"caption":"Escuela Superior de Inform\u00e1tica de UCLM"},"image":{"@id":"https:\/\/esi.uclm.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Escuela-Superior-de-Informtica-543261809027158","https:\/\/x.com\/esiuclm","https:\/\/www.instagram.com\/esiuclm\/","https:\/\/www.youtube.com\/user\/esiuclm","https:\/\/www.twitch.tv\/esiuclm","https:\/\/www.linkedin.com\/company\/12656631\/admin\/"]},{"@type":"Person","@id":"https:\/\/esi.uclm.es\/#\/schema\/person\/d9a390095e8beeca5aced92acb17a530","name":"esiuclm","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff32e6f445454691c713484fe154c7002761ecabfa4cfa2fea57c231744892da?s=96&d=mm&r=g","caption":"esiuclm"},"sameAs":["https:\/\/esi.uclm.es"],"url":"https:\/\/esi.uclm.es\/index.php\/author\/esiadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/15338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/comments?post=15338"}],"version-history":[{"count":4,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/15338\/revisions"}],"predecessor-version":[{"id":15354,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/posts\/15338\/revisions\/15354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/media\/15339"}],"wp:attachment":[{"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/media?parent=15338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/categories?post=15338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esi.uclm.es\/index.php\/wp-json\/wp\/v2\/tags?post=15338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}